{"id":2689,"date":"2024-04-16T15:23:26","date_gmt":"2024-04-16T15:23:26","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/"},"modified":"2024-07-31T11:19:47","modified_gmt":"2024-07-31T14:19:47","slug":"kbom-universitario-cd-12-materias-capa-f","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-12-materias-capa-f\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 12 mat\u00e9rias &#8211; Capa F"},"author":1,"featured_media":8963,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[270],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2689","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-270","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10153","ean":"7891321101537","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2684,2685,2686,2687,2688,2690,2691],"related_products":[{"id":2668,"date":"2024-04-16T15:23:20","date_gmt":"2024-04-16T15:23:20","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/"},"modified":"2024-07-31T11:28:03","modified_gmt":"2024-07-31T14:28:03","slug":"kbom-universitario-cd-1-materia-capa-a","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-1-materia-capa-a\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 1 mat\u00e9ria &#8211; Capa A"},"author":1,"featured_media":8953,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[272],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2668","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-272","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10151","ean":"7891321101513","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2669,2670,2671,2672,2673,2674,2675],"related_products":[{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-01.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":272,"name":"96","slug":"96"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2668\/revisions"}],"predecessor-version":[{"id":19214,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2668\/revisions\/19214"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8953"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2668"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2668"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2668"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2668"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2668"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2668"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2668"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2668"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2668"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2669,"date":"2024-04-16T15:23:21","date_gmt":"2024-04-16T15:23:21","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/"},"modified":"2024-07-31T11:26:41","modified_gmt":"2024-07-31T14:26:41","slug":"kbom-universitario-cd-1-materia-capa-b","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-1-materia-capa-b\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 1 mat\u00e9ria &#8211; Capa B"},"author":1,"featured_media":8955,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[272],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2669","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-272","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10151","ean":"7891321101513","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2668,2670,2671,2672,2673,2674,2675],"related_products":[{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-02.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":272,"name":"96","slug":"96"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2669\/revisions"}],"predecessor-version":[{"id":19210,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2669\/revisions\/19210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8955"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2669"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2669"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2669"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2669"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2669"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2669"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2669"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2669"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2669"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2670,"date":"2024-04-16T15:23:21","date_gmt":"2024-04-16T15:23:21","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/"},"modified":"2024-07-31T11:26:59","modified_gmt":"2024-07-31T14:26:59","slug":"kbom-universitario-cd-1-materia-capa-c","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-1-materia-capa-c\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 1 mat\u00e9ria &#8211; Capa C"},"author":1,"featured_media":8957,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[272],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2670","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-272","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10151","ean":"7891321101513","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2668,2669,2671,2672,2673,2674,2675],"related_products":[{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-03.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":272,"name":"96","slug":"96"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2670\/revisions"}],"predecessor-version":[{"id":19211,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2670\/revisions\/19211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8957"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2670"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2670"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2670"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2670"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2670"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2670"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2670"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2670"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2670"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2671,"date":"2024-04-16T15:23:21","date_gmt":"2024-04-16T15:23:21","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/"},"modified":"2024-07-31T11:27:16","modified_gmt":"2024-07-31T14:27:16","slug":"kbom-universitario-cd-1-materia-capa-d","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-1-materia-capa-d\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 1 mat\u00e9ria &#8211; Capa D"},"author":1,"featured_media":8959,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[272],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2671","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-272","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10151","ean":"7891321101513","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2668,2669,2670,2672,2673,2674,2675],"related_products":[{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-04.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":272,"name":"96","slug":"96"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2671\/revisions"}],"predecessor-version":[{"id":19212,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2671\/revisions\/19212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8959"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2671"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2671"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2671"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2671"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2671"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2671"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2671"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2671"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2671"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2672,"date":"2024-04-16T15:23:21","date_gmt":"2024-04-16T15:23:21","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/"},"modified":"2024-07-31T11:27:42","modified_gmt":"2024-07-31T14:27:42","slug":"kbom-universitario-cd-1-materia-capa-e","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-1-materia-capa-e\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 1 mat\u00e9ria &#8211; Capa E"},"author":1,"featured_media":8961,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[272],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2672","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-272","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10151","ean":"7891321101513","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2668,2669,2670,2671,2673,2674,2675],"related_products":[{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-05.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":272,"name":"96","slug":"96"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2672\/revisions"}],"predecessor-version":[{"id":19213,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2672\/revisions\/19213"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8961"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2672"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2672"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2672"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2672"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2672"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2672"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2672"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2672"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2672"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2673,"date":"2024-04-16T15:23:22","date_gmt":"2024-04-16T15:23:22","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/"},"modified":"2024-07-31T11:25:24","modified_gmt":"2024-07-31T14:25:24","slug":"kbom-universitario-cd-1-materia-capa-f","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-1-materia-capa-f\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 1 mat\u00e9ria &#8211; Capa F"},"author":1,"featured_media":8963,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[272],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2673","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-272","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10151","ean":"7891321101513","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2668,2669,2670,2671,2672,2674,2675],"related_products":[{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-06.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":272,"name":"96","slug":"96"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2673\/revisions"}],"predecessor-version":[{"id":19206,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2673\/revisions\/19206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8963"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2673"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2673"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2673"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2673"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2673"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2673"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2673"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2673"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2673"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2674,"date":"2024-04-16T15:23:22","date_gmt":"2024-04-16T15:23:22","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/"},"modified":"2024-07-31T11:25:40","modified_gmt":"2024-07-31T14:25:40","slug":"kbom-universitario-cd-1-materia-capa-g","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-1-materia-capa-g\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 1 mat\u00e9ria &#8211; Capa G"},"author":1,"featured_media":8965,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[272],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2674","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-272","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10151","ean":"7891321101513","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2668,2669,2670,2671,2672,2673,2675],"related_products":[{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-07.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":272,"name":"96","slug":"96"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2674\/revisions"}],"predecessor-version":[{"id":19207,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2674\/revisions\/19207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8965"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2674"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2674"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2674"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2674"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2674"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2674"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2674"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2674"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2674"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2675,"date":"2024-04-16T15:23:22","date_gmt":"2024-04-16T15:23:22","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/"},"modified":"2024-07-31T11:26:00","modified_gmt":"2024-07-31T14:26:00","slug":"kbom-universitario-cd-1-materia-capa-h","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-1-materia-capa-h\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 1 mat\u00e9ria &#8211; Capa H"},"author":1,"featured_media":8967,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[272],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2675","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-272","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10151","ean":"7891321101513","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2668,2669,2670,2671,2672,2673,2674],"related_products":[{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-08.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":272,"name":"96","slug":"96"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2675\/revisions"}],"predecessor-version":[{"id":19208,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2675\/revisions\/19208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8967"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2675"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2675"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2675"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2675"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2675"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2675"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2675"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2675"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2675"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2676,"date":"2024-04-16T15:23:22","date_gmt":"2024-04-16T15:23:22","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/"},"modified":"2024-07-31T11:26:23","modified_gmt":"2024-07-31T14:26:23","slug":"kbom-universitario-cd-10-materias-capa-a","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-10-materias-capa-a\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 10 mat\u00e9rias &#8211; Capa A"},"author":1,"featured_media":8953,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[274],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2676","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-274","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10152","ean":"7891321101520","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2677,2678,2679,2680,2681,2682,2683],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-01.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":274,"name":"200","slug":"200"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2676\/revisions"}],"predecessor-version":[{"id":19209,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2676\/revisions\/19209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8953"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2676"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2676"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2676"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2676"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2676"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2676"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2676"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2676"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2676"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2677,"date":"2024-04-16T15:23:23","date_gmt":"2024-04-16T15:23:23","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/"},"modified":"2024-07-31T11:24:12","modified_gmt":"2024-07-31T14:24:12","slug":"kbom-universitario-cd-10-materias-capa-b","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-10-materias-capa-b\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 10 mat\u00e9rias &#8211; Capa B"},"author":1,"featured_media":8955,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[274],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2677","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-274","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10152","ean":"7891321101520","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2676,2678,2679,2680,2681,2682,2683],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-02.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":274,"name":"200","slug":"200"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2677\/revisions"}],"predecessor-version":[{"id":19202,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2677\/revisions\/19202"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8955"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2677"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2677"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2677"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2677"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2677"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2677"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2677"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2677"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2677"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2678,"date":"2024-04-16T15:23:23","date_gmt":"2024-04-16T15:23:23","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/"},"modified":"2024-07-31T11:24:27","modified_gmt":"2024-07-31T14:24:27","slug":"kbom-universitario-cd-10-materias-capa-c","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-10-materias-capa-c\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 10 mat\u00e9rias &#8211; Capa C"},"author":1,"featured_media":8957,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[274],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2678","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-274","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10152","ean":"7891321101520","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2676,2677,2679,2680,2681,2682,2683],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-03.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":274,"name":"200","slug":"200"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2678\/revisions"}],"predecessor-version":[{"id":19203,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2678\/revisions\/19203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8957"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2678"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2678"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2678"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2678"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2678"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2678"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2678"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2678"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2678"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2679,"date":"2024-04-16T15:23:23","date_gmt":"2024-04-16T15:23:23","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/"},"modified":"2024-07-31T11:24:47","modified_gmt":"2024-07-31T14:24:47","slug":"kbom-universitario-cd-10-materias-capa-d","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-10-materias-capa-d\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 10 mat\u00e9rias &#8211; Capa D"},"author":1,"featured_media":8959,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[274],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2679","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-274","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10152","ean":"7891321101520","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2676,2677,2678,2680,2681,2682,2683],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-04.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":274,"name":"200","slug":"200"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2679\/revisions"}],"predecessor-version":[{"id":19204,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2679\/revisions\/19204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8959"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2679"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2679"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2679"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2679"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2679"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2679"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2679"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2679"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2679"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2680,"date":"2024-04-16T15:23:23","date_gmt":"2024-04-16T15:23:23","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/"},"modified":"2024-07-31T11:25:01","modified_gmt":"2024-07-31T14:25:01","slug":"kbom-universitario-cd-10-materias-capa-e","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-10-materias-capa-e\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 10 mat\u00e9rias &#8211; Capa E"},"author":1,"featured_media":8961,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[274],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2680","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-274","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10152","ean":"7891321101520","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2676,2677,2678,2679,2681,2682,2683],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-05.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":274,"name":"200","slug":"200"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2680\/revisions"}],"predecessor-version":[{"id":19205,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2680\/revisions\/19205"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8961"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2680"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2680"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2680"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2680"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2680"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2680"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2680"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2680"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2680"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2681,"date":"2024-04-16T15:23:24","date_gmt":"2024-04-16T15:23:24","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/"},"modified":"2024-07-31T11:22:34","modified_gmt":"2024-07-31T14:22:34","slug":"kbom-universitario-cd-10-materias-capa-f","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-10-materias-capa-f\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 10 mat\u00e9rias &#8211; Capa F"},"author":1,"featured_media":8963,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[274],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2681","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-274","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10152","ean":"7891321101520","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2676,2677,2678,2679,2680,2682,2683],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-06.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":274,"name":"200","slug":"200"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2681\/revisions"}],"predecessor-version":[{"id":19198,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2681\/revisions\/19198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8963"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2681"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2681"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2681"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2681"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2681"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2681"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2681"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2681"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2681"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2682,"date":"2024-04-16T15:23:24","date_gmt":"2024-04-16T15:23:24","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/"},"modified":"2024-07-31T11:22:53","modified_gmt":"2024-07-31T14:22:53","slug":"kbom-universitario-cd-10-materias-capa-g","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-10-materias-capa-g\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 10 mat\u00e9rias &#8211; Capa G"},"author":1,"featured_media":8965,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[274],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2682","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-274","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10152","ean":"7891321101520","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2676,2677,2678,2679,2680,2681,2683],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-07.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":274,"name":"200","slug":"200"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2682\/revisions"}],"predecessor-version":[{"id":19199,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2682\/revisions\/19199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8965"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2682"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2682"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2682"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2682"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2682"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2682"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2682"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2682"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2682"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2683,"date":"2024-04-16T15:23:24","date_gmt":"2024-04-16T15:23:24","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/"},"modified":"2024-07-31T11:23:26","modified_gmt":"2024-07-31T14:23:26","slug":"kbom-universitario-cd-10-materias-capa-h","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-10-materias-capa-h\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 10 mat\u00e9rias &#8211; Capa H"},"author":1,"featured_media":8967,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[274],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2683","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-274","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10152","ean":"7891321101520","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2676,2677,2678,2679,2680,2681,2682],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-08.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":274,"name":"200","slug":"200"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2683\/revisions"}],"predecessor-version":[{"id":19200,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2683\/revisions\/19200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8967"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2683"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2683"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2683"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2683"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2683"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2683"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2683"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2683"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2683"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2692,"date":"2024-04-16T15:23:27","date_gmt":"2024-04-16T15:23:27","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/"},"modified":"2024-07-31T11:17:49","modified_gmt":"2024-07-31T14:17:49","slug":"kbom-universitario-cd-15-materias-capa-a","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-15-materias-capa-a\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 15 mat\u00e9rias &#8211; Capa A"},"author":1,"featured_media":8953,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[276],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2692","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-276","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10154","ean":"7891321101537","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2693,2694,2695,2696,2697,2698,2699],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-01.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":276,"name":"300","slug":"300"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2692\/revisions"}],"predecessor-version":[{"id":19187,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2692\/revisions\/19187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8953"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2692"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2692"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2692"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2692"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2692"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2692"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2692"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2692"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2692"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2693,"date":"2024-04-16T15:23:27","date_gmt":"2024-04-16T15:23:27","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/"},"modified":"2024-07-31T11:18:17","modified_gmt":"2024-07-31T14:18:17","slug":"kbom-universitario-cd-15-materias-capa-b","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-15-materias-capa-b\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 15 mat\u00e9rias &#8211; Capa B"},"author":1,"featured_media":8955,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[276],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2693","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-276","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10154","ean":"7891321101537","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2692,2694,2695,2696,2697,2698,2699],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-02.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":276,"name":"300","slug":"300"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2693\/revisions"}],"predecessor-version":[{"id":19188,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2693\/revisions\/19188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8955"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2693"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2693"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2693"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2693"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2693"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2693"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2693"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2693"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2693"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2694,"date":"2024-04-16T15:23:27","date_gmt":"2024-04-16T15:23:27","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/"},"modified":"2024-07-31T11:18:43","modified_gmt":"2024-07-31T14:18:43","slug":"kbom-universitario-cd-15-materias-capa-c","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-15-materias-capa-c\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 15 mat\u00e9rias &#8211; Capa C"},"author":1,"featured_media":8957,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[276],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2694","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-276","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10154","ean":"7891321101537","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2692,2693,2695,2696,2697,2698,2699],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-03.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":276,"name":"300","slug":"300"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2694\/revisions"}],"predecessor-version":[{"id":19189,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2694\/revisions\/19189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8957"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2694"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2694"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2694"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2694"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2694"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2694"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2694"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2694"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2694"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2695,"date":"2024-04-16T15:23:27","date_gmt":"2024-04-16T15:23:27","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/"},"modified":"2024-07-31T11:19:08","modified_gmt":"2024-07-31T14:19:08","slug":"kbom-universitario-cd-15-materias-capa-d","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-15-materias-capa-d\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 15 mat\u00e9rias &#8211; Capa D"},"author":1,"featured_media":8959,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[276],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2695","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-276","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10154","ean":"7891321101537","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2692,2693,2694,2696,2697,2698,2699],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-04.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":276,"name":"300","slug":"300"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2695\/revisions"}],"predecessor-version":[{"id":19190,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2695\/revisions\/19190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8959"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2695"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2695"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2695"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2695"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2695"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2695"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2695"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2695"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2695"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2696,"date":"2024-04-16T15:23:28","date_gmt":"2024-04-16T15:23:28","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/"},"modified":"2024-07-31T11:15:24","modified_gmt":"2024-07-31T14:15:24","slug":"kbom-universitario-cd-15-materias-capa-e","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-15-materias-capa-e\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 15 mat\u00e9rias &#8211; Capa E"},"author":1,"featured_media":8961,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[276],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2696","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-276","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10154","ean":"7891321101537","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2692,2693,2694,2695,2697,2698,2699],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-05.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":276,"name":"300","slug":"300"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2696\/revisions"}],"predecessor-version":[{"id":19183,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2696\/revisions\/19183"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8961"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2696"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2696"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2696"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2696"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2696"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2696"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2696"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2696"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2696"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2697,"date":"2024-04-16T15:23:28","date_gmt":"2024-04-16T15:23:28","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/"},"modified":"2024-07-31T11:15:56","modified_gmt":"2024-07-31T14:15:56","slug":"kbom-universitario-cd-15-materias-capa-f","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-15-materias-capa-f\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 15 mat\u00e9rias &#8211; Capa F"},"author":1,"featured_media":8963,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[276],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2697","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-276","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10154","ean":"7891321101537","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2692,2693,2694,2695,2696,2698,2699],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-06.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":276,"name":"300","slug":"300"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2697\/revisions"}],"predecessor-version":[{"id":19184,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2697\/revisions\/19184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8963"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2697"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2697"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2697"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2697"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2697"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2697"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2697"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2697"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2697"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2698,"date":"2024-04-16T15:23:28","date_gmt":"2024-04-16T15:23:28","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/"},"modified":"2024-07-31T11:17:16","modified_gmt":"2024-07-31T14:17:16","slug":"kbom-universitario-cd-15-materias-capa-g","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-15-materias-capa-g\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 15 mat\u00e9rias &#8211; Capa G"},"author":1,"featured_media":8965,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[276],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2698","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-276","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10154","ean":"7891321101537","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":false},"variants":[2692,2693,2694,2695,2696,2697,2699],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-07.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":276,"name":"300","slug":"300"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2698\/revisions"}],"predecessor-version":[{"id":19185,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2698\/revisions\/19185"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8965"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2698"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2698"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2698"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2698"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2698"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2698"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2698"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2698"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2698"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2699,"date":"2024-04-16T15:23:28","date_gmt":"2024-04-16T15:23:28","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/"},"modified":"2024-07-31T11:17:36","modified_gmt":"2024-07-31T14:17:36","slug":"kbom-universitario-cd-15-materias-capa-h","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-15-materias-capa-h\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 15 mat\u00e9rias &#8211; Capa H"},"author":1,"featured_media":8967,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[276],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2699","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-276","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10154","ean":"7891321101537","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2692,2693,2694,2695,2696,2697,2698],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2700,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa A","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:11","post_modified_gmt":"2024-07-31 14:13:11","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2701,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa B","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:13:44","post_modified_gmt":"2024-07-31 14:13:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2702,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa C","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:21","post_modified_gmt":"2024-07-31 14:14:21","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2703,"post_author":"1","post_date":"2024-04-16 15:23:29","post_date_gmt":"2024-04-16 15:23:29","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa D","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:14:50","post_modified_gmt":"2024-07-31 14:14:50","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2704,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa E","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:10:37","post_modified_gmt":"2024-07-31 14:10:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2705,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa F","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:05","post_modified_gmt":"2024-07-31 14:11:05","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2706,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa G","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:23","post_modified_gmt":"2024-07-31 14:11:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2707,"post_author":"1","post_date":"2024-04-16 15:23:30","post_date_gmt":"2024-04-16 15:23:30","post_content":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 20 mat\u00e9rias - Capa H","post_excerpt":"KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-20-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:11:59","post_modified_gmt":"2024-07-31 14:11:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-08.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":276,"name":"300","slug":"300"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2699\/revisions"}],"predecessor-version":[{"id":19186,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2699\/revisions\/19186"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8967"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2699"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2699"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2699"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2699"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2699"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2699"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2699"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2699"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2699"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2700,"date":"2024-04-16T15:23:29","date_gmt":"2024-04-16T15:23:29","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-a\/"},"modified":"2024-07-31T11:13:11","modified_gmt":"2024-07-31T14:13:11","slug":"kbom-universitario-cd-20-materias-capa-a","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-20-materias-capa-a\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 20 mat\u00e9rias &#8211; Capa A"},"author":1,"featured_media":8953,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[275],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2700","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-275","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10155","ean":"7891321101551","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2701,2702,2703,2704,2705,2706,2707],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-01.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":275,"name":"400","slug":"400"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":12,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2700\/revisions"}],"predecessor-version":[{"id":19179,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2700\/revisions\/19179"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8953"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2700"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2700"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2700"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2700"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2700"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2700"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2700"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2700"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2700"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2701,"date":"2024-04-16T15:23:29","date_gmt":"2024-04-16T15:23:29","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-b\/"},"modified":"2024-07-31T11:13:44","modified_gmt":"2024-07-31T14:13:44","slug":"kbom-universitario-cd-20-materias-capa-b","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-20-materias-capa-b\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 20 mat\u00e9rias &#8211; Capa B"},"author":1,"featured_media":8955,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[275],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2701","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-275","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10155","ean":"7891321101551","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2700,2702,2703,2704,2705,2706,2707],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-02.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":275,"name":"400","slug":"400"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":12,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2701\/revisions"}],"predecessor-version":[{"id":19180,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2701\/revisions\/19180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8955"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2701"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2701"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2701"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2701"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2701"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2701"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2701"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2701"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2701"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2702,"date":"2024-04-16T15:23:29","date_gmt":"2024-04-16T15:23:29","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-c\/"},"modified":"2024-07-31T11:14:21","modified_gmt":"2024-07-31T14:14:21","slug":"kbom-universitario-cd-20-materias-capa-c","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-20-materias-capa-c\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 20 mat\u00e9rias &#8211; Capa C"},"author":1,"featured_media":8957,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[275],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409,404],"class_list":["post-2702","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-275","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura","produto_caracteristica-libras"],"acf":{"infos_produto":{"sku":"10155","ean":"7891321101551","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2700,2701,2703,2704,2705,2706,2707],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-03.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":275,"name":"400","slug":"400"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":11,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2702\/revisions"}],"predecessor-version":[{"id":19181,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2702\/revisions\/19181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8957"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2702"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2702"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2702"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2702"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2702"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2702"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2702"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2702"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2702"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2703,"date":"2024-04-16T15:23:29","date_gmt":"2024-04-16T15:23:29","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-d\/"},"modified":"2024-07-31T11:14:50","modified_gmt":"2024-07-31T14:14:50","slug":"kbom-universitario-cd-20-materias-capa-d","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-20-materias-capa-d\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 20 mat\u00e9rias &#8211; Capa D"},"author":1,"featured_media":8959,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[275],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2703","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-275","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10155","ean":"7891321101551","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2700,2701,2702,2704,2705,2706,2707],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-04.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":275,"name":"400","slug":"400"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":11,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2703\/revisions"}],"predecessor-version":[{"id":19182,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2703\/revisions\/19182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8959"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2703"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2703"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2703"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2703"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2703"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2703"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2703"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2703"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2703"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2704,"date":"2024-04-16T15:23:30","date_gmt":"2024-04-16T15:23:30","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-e\/"},"modified":"2024-07-31T11:10:37","modified_gmt":"2024-07-31T14:10:37","slug":"kbom-universitario-cd-20-materias-capa-e","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-20-materias-capa-e\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 20 mat\u00e9rias &#8211; Capa E"},"author":1,"featured_media":8961,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[275],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2704","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-275","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10155","ean":"7891321101551","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2700,2701,2702,2703,2705,2706,2707],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-05.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":275,"name":"400","slug":"400"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2704","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":13,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2704\/revisions"}],"predecessor-version":[{"id":19174,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2704\/revisions\/19174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8961"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2704"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2704"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2704"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2704"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2704"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2704"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2704"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2704"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2704"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2704"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2705,"date":"2024-04-16T15:23:30","date_gmt":"2024-04-16T15:23:30","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-f\/"},"modified":"2024-07-31T11:11:05","modified_gmt":"2024-07-31T14:11:05","slug":"kbom-universitario-cd-20-materias-capa-f","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-20-materias-capa-f\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 20 mat\u00e9rias &#8211; Capa F"},"author":1,"featured_media":8963,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[275],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2705","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-275","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10155","ean":"7891321101551","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2700,2701,2702,2703,2704,2706,2707],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-06.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":275,"name":"400","slug":"400"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":11,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2705\/revisions"}],"predecessor-version":[{"id":19175,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2705\/revisions\/19175"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8963"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2705"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2705"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2705"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2705"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2705"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2705"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2705"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2705"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2705"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2706,"date":"2024-04-16T15:23:30","date_gmt":"2024-04-16T15:23:30","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-g\/"},"modified":"2024-07-31T11:11:23","modified_gmt":"2024-07-31T14:11:23","slug":"kbom-universitario-cd-20-materias-capa-g","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-20-materias-capa-g\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 20 mat\u00e9rias &#8211; Capa G"},"author":1,"featured_media":8965,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[275],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2706","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-275","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10155","ean":"7891321101551","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2700,2701,2702,2703,2704,2705,2707],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-07.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":275,"name":"400","slug":"400"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":11,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2706\/revisions"}],"predecessor-version":[{"id":19176,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2706\/revisions\/19176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8965"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2706"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2706"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2706"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2706"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2706"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2706"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2706"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2706"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2706"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":2707,"date":"2024-04-16T15:23:30","date_gmt":"2024-04-16T15:23:30","guid":{"rendered":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-20-materias-capa-h\/"},"modified":"2024-07-31T11:11:59","modified_gmt":"2024-07-31T14:11:59","slug":"kbom-universitario-cd-20-materias-capa-h","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/pt-br\/p\/kbom-universitario-cd-20-materias-capa-h\/","title":{"rendered":"Kbom!  \u2013 Universit\u00e1rio CD &#8211; 20 mat\u00e9rias &#8211; Capa H"},"author":1,"featured_media":8967,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[275],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409],"class_list":["post-2707","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-275","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura"],"acf":{"infos_produto":{"sku":"10155","ean":"7891321101551","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>KBOM! \u00e9 mais do que uma cole\u00e7\u00e3o de cadernos, \u00e9 um verdadeiro estilo de vida. Com suas variadas estampas e qualidade excepcional, essa linha da Animativa promete agradar a todos os gostos e estilos.<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":false,"adesivos":true},"variants":[2700,2701,2702,2703,2704,2705,2706],"related_products":[{"ID":2668,"post_author":"1","post_date":"2024-04-16 15:23:20","post_date_gmt":"2024-04-16 15:23:20","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa A","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:28:03","post_modified_gmt":"2024-07-31 14:28:03","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2669,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa B","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:41","post_modified_gmt":"2024-07-31 14:26:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2670,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa C","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:59","post_modified_gmt":"2024-07-31 14:26:59","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2671,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa D","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:16","post_modified_gmt":"2024-07-31 14:27:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2672,"post_author":"1","post_date":"2024-04-16 15:23:21","post_date_gmt":"2024-04-16 15:23:21","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa E","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:27:42","post_modified_gmt":"2024-07-31 14:27:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2673,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa F","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:24","post_modified_gmt":"2024-07-31 14:25:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2674,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa G","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:40","post_modified_gmt":"2024-07-31 14:25:40","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2675,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 1 mat\u00e9ria - Capa H","post_excerpt":"KBOM! \u00e9 sin\u00f4nimo de sucesso na linha de cadernos da Animativa. Com suas variadas estampas e qualidade inigual\u00e1vel, essa cole\u00e7\u00e3o \u00e9 uma escolha certeira para quem busca estilo e versatilidade.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-1-materia-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:00","post_modified_gmt":"2024-07-31 14:26:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-1-materia-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2676,"post_author":"1","post_date":"2024-04-16 15:23:22","post_date_gmt":"2024-04-16 15:23:22","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa A","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:26:23","post_modified_gmt":"2024-07-31 14:26:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2677,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa B","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:12","post_modified_gmt":"2024-07-31 14:24:12","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2678,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa C","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:27","post_modified_gmt":"2024-07-31 14:24:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2679,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa D","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:24:47","post_modified_gmt":"2024-07-31 14:24:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2680,"post_author":"1","post_date":"2024-04-16 15:23:23","post_date_gmt":"2024-04-16 15:23:23","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa E","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:25:01","post_modified_gmt":"2024-07-31 14:25:01","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2681,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa F","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:34","post_modified_gmt":"2024-07-31 14:22:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2682,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa G","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:53","post_modified_gmt":"2024-07-31 14:22:53","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2683,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 10 mat\u00e9rias - Capa H","post_excerpt":"Convidamos voc\u00ea a conhecer a linha KBOM! da Animativa, que \u00e9 sucesso absoluto gra\u00e7as \u00e0 sua variedade de estampas e qualidade excepcional. N\u00e3o perca a chance de encontrar o caderno perfeito para voc\u00ea!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-10-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:26","post_modified_gmt":"2024-07-31 14:23:26","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-10-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2684,"post_author":"1","post_date":"2024-04-16 15:23:24","post_date_gmt":"2024-04-16 15:23:24","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa A","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:23:45","post_modified_gmt":"2024-07-31 14:23:45","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2685,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa B","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:04","post_modified_gmt":"2024-07-31 14:21:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2686,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa C","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:21:34","post_modified_gmt":"2024-07-31 14:21:34","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2687,"post_author":"1","post_date":"2024-04-16 15:23:25","post_date_gmt":"2024-04-16 15:23:25","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa D","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:22:18","post_modified_gmt":"2024-07-31 14:22:18","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2688,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa E","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:27","post_modified_gmt":"2024-07-31 14:19:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2689,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa F","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:47","post_modified_gmt":"2024-07-31 14:19:47","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2690,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa G","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:20","post_modified_gmt":"2024-07-31 14:20:20","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2691,"post_author":"1","post_date":"2024-04-16 15:23:26","post_date_gmt":"2024-04-16 15:23:26","post_content":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 12 mat\u00e9rias - Capa H","post_excerpt":"Quer arrasar com um caderno cheio de estilo? Ent\u00e3o voc\u00ea precisa conhecer a linha KBOM! da Animativa. Com suas estampas variadas e qualidade impec\u00e1vel, esses cadernos s\u00e3o uma escolha certeira.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-12-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:20:42","post_modified_gmt":"2024-07-31 14:20:42","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-12-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2692,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa A","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:49","post_modified_gmt":"2024-07-31 14:17:49","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2693,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa B","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:17","post_modified_gmt":"2024-07-31 14:18:17","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2694,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa C","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-07-31 11:18:43","post_modified_gmt":"2024-07-31 14:18:43","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2695,"post_author":"1","post_date":"2024-04-16 15:23:27","post_date_gmt":"2024-04-16 15:23:27","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa D","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-07-31 11:19:08","post_modified_gmt":"2024-07-31 14:19:08","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2696,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa E","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-e","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:24","post_modified_gmt":"2024-07-31 14:15:24","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-e\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2697,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa F","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-f","to_ping":"","pinged":"","post_modified":"2024-07-31 11:15:56","post_modified_gmt":"2024-07-31 14:15:56","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-f\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2698,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa G","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-g","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:16","post_modified_gmt":"2024-07-31 14:17:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-g\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":2699,"post_author":"1","post_date":"2024-04-16 15:23:28","post_date_gmt":"2024-04-16 15:23:28","post_content":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_title":"Kbom!  \u2013 Universit\u00e1rio CD - 15 mat\u00e9rias - Capa H","post_excerpt":"Se voc\u00ea busca por cadernos vers\u00e1teis e cheios de personalidade, a linha KBOM! da Animativa \u00e9 a escolha perfeita. Com suas variadas estampas e qualidade indiscut\u00edvel, esses cadernos v\u00e3o conquistar voc\u00ea.","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"kbom-universitario-cd-15-materias-capa-h","to_ping":"","pinged":"","post_modified":"2024-07-31 11:17:36","post_modified_gmt":"2024-07-31 14:17:36","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/kbom-universitario-cd-15-materias-capa-h\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-08.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":275,"name":"400","slug":"400"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2707\/revisions"}],"predecessor-version":[{"id":19177,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2707\/revisions\/19177"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8967"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2707"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2707"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2707"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2707"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2707"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2707"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2707"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2707"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2707"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"where_to_find":{"animativa_ecommerce_url":"","online_stores":false,"local_stores":false},"product_type":85,"brand":4354},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/pt-br\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":4354,"date":"2024-04-15T21:20:11","date_gmt":"2024-04-15T21:20:11","guid":{"rendered":"http:\/\/animativa.local\/marcas_produtos\/kbom-2\/"},"modified":"2024-07-27T17:29:25","modified_gmt":"2024-07-27T20:29:25","slug":"kbom-masc","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/pt-br\/marcas\/kbom-masc\/","title":{"rendered":"KBOM! Masculino"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-4354","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":8,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions"}],"predecessor-version":[{"id":18572,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/marcas\/4354\/revisions\/18572"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=4354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/KabomMarculino-06.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":270,"name":"240","slug":"240"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2689\/revisions"}],"predecessor-version":[{"id":19192,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produtos\/2689\/revisions\/19192"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/8963"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=2689"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categoria_produtos?post=2689"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_capa?post=2689"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_lombada?post=2689"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_tipo_folha?post=2689"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_folha?post=2689"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_gramatura?post=2689"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_formato_mm?post=2689"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_selo?post=2689"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/produto_caracteristica?post=2689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}