{"id":30624,"date":"2024-08-09T19:57:28","date_gmt":"2024-08-09T22:57:28","guid":{"rendered":"https:\/\/dev.animativa.com\/pt-br\/blog\/canal-brancoala\/"},"modified":"2024-08-09T19:57:28","modified_gmt":"2024-08-09T22:57:28","slug":"canal-brancoala","status":"publish","type":"post","link":"https:\/\/dev.animativa.com\/pt-br\/blog\/canal-brancoala\/","title":{"rendered":"Canal Brancoala: Dia a Dia de Uma Fam\u00edlia Style"},"content":{"rendered":"<p>Quando pensamos nos famigerados \u201ccases de sucesso\u201d, surgem sempre as mesmas hist\u00f3rias repetidas e recheadas de clich\u00eas. N\u00e3o \u00e9 t\u00e3o f\u00e1cil encontrar um modelo de neg\u00f3cio verdadeiramente disruptor e que deu certo de verdade. Uma dessas exce\u00e7\u00f5es \u00e9 o <a href=\"https:\/\/www.youtube.com\/channel\/UC0otZdGYsA9KqVKAcn2peQA\" target=\"_blank\" rel=\"noopener\">Canal Brancoala<\/a>, no Youtube. Branco, o idealizador do canal, posta de segunda a sexta-feira v\u00eddeos compartilhando sua rotina em fam\u00edlia: passeios, dia a dia da fam\u00edlia em casa, jogos, desafios e v\u00eddeos de games\u2026 Resultado? Mais de 1.500 v\u00eddeos, o maior canal do YouTube Brasil na categoria fam\u00edlia, mais de 10 milh\u00f5es de inscritos e 6 bilh\u00f5es de visualiza\u00e7\u00f5es! E isso apenas no Youtube&#8230; Esse, sim, \u00e9 um \u201ccase de sucesso\u201d que vale a pena conhecer.<\/p>\n<h2 class=\"wp-block-heading\">Fam\u00edlia Brancoala<\/h2>\n<p>Cl\u00e1udia, carinhosamente chamada de \u201cCraudete\u201d, \u00e9 a estrela da fam\u00edlia. M\u00e3e de dois, ela brilha na cozinha, \u00e9 uma organizadora nata, guerreira e sempre atenta \u00e0s economias. Marcos, tamb\u00e9m conhecido como \u201cMaikito\u201d, \u00e9 o filho mais velho. Ele adora atividades f\u00edsicas, como pular, correr, jogar bola, andar de bicicleta e jogar videogame. Laura, ou \u201cLaurinha\u201d, \u00e9 a ca\u00e7ula da fam\u00edlia. F\u00e3 das princesas da Disney, de m\u00fasicas animadas e j\u00e1 foi confundida com uma beb\u00ea reborn. Branco, conhecido como \u201cBrancoala\u201d, \u00e9 o pai estiloso. Ele passa grande parte do tempo gravando e editando v\u00eddeos, bebendo chimarr\u00e3o, tocando viol\u00e3o e brincando com seus carrinhos Hot Wheels.<\/p>\n<h2 class=\"wp-block-heading\">Hist\u00f3ria<\/h2>\n<p>A hist\u00f3ria da fam\u00edlia Brancoala come\u00e7ou em 2004, na cidade de Praia Grande, SP, Brasil, quando Branco conheceu Cl\u00e1udia em um banho e tosa. O amor entre eles foi quase instant\u00e2neo. Entre espumas e pelos de cachorros, eles come\u00e7aram a namorar e, em menos de seis meses, j\u00e1 estavam morando juntos e fazendo planos. Em 2006, buscando novas oportunidades, o casal se mudou para a Espanha, devido \u00e0 dif\u00edcil situa\u00e7\u00e3o econ\u00f4mica no Brasil. Eles venderam seus poucos pertences, incluindo m\u00f3veis, eletrodom\u00e9sticos e objetos pessoais, para financiar a viagem. Na Espanha, enfrentaram tempos desafiadores, trabalhando com limpeza, constru\u00e7\u00e3o, pintura, distribui\u00e7\u00e3o de panfletos, colheita de azeitonas, em restaurantes e outros empregos tempor\u00e1rios para sobreviver. O casal chegou a trabalhar 16 horas di\u00e1rias para cobrir as despesas. Em abril de 2014, a vida deles mudou com o nascimento do primeiro filho, Marcos. Com a chegada do beb\u00ea, equilibrar trabalho, fam\u00edlia e o canal do YouTube tornou-se dif\u00edcil, levando-os a interromper a postagem de v\u00eddeos por seis meses. Eventualmente, Branco pediu demiss\u00e3o do emprego e dedicou-se integralmente ao canal e \u00e0 fam\u00edlia.<\/p>\n<h2 class=\"wp-block-heading\">Daily Vlogs<\/h2>\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<\/div>\n<\/figure>\n<p>Em 2015, a fam\u00edlia Brancoala come\u00e7ou a compartilhar sua rotina di\u00e1ria, transformando o canal, que antes era focado em m\u00fasica, em um espa\u00e7o para daily vlogs. Branco criou um novo canal para suas m\u00fasicas autorais. Em abril de 2017, nasceu a segunda filha, Laura, tornando a rotina da fam\u00edlia ainda mais animada e divertida. Atualmente, eles residem em Orlando, nos Estados Unidos, onde continuam produzindo conte\u00fados para o Canal Brancoala, encantando seus seguidores com o dia a dia da fam\u00edlia.<\/p>\n<h2 class=\"wp-block-heading\">Universo Brancoala<\/h2>\n<p>O sucesso do canal no Youtube \u00e9 t\u00e3o grande, que o projeto Brancoala rompou as barreiras do streaming e hoje em dia conta com diversos outros conte\u00fados, olha s\u00f3:<\/p>\n<p><strong>\u2022 Loja:<\/strong> Camisetas, meias, bon\u00e9s, cadernos, fones de ouvido, teclados de computador, mousepads, mochilas, pijamas\u2026 Voltada para o p\u00fablico infantil, a Loja Brancoala conta com diversos produtos.<\/p>\n<p><strong>\u2022 M\u00fasicas:<\/strong> Lembra que o Branco ama m\u00fasica? Mesmo com o sucesso do Canal Brancoala, ele n\u00e3o deixou essa paix\u00e3o de lado. Pelo contr\u00e1rio! Voc\u00ea pode escutar as m\u00fasicas do Brancoala nas principais plataformas digitais!<\/p>\n<p><strong>\u2022 Blog: <\/strong>Artigos completos? O time Brancoala tamb\u00e9m produz. O blog \u00e9 dividido em tr\u00eas sess\u00f5es de assunto:<\/p>\n<ul class=\"wp-block-list\">\n<li>Receitas: Canal onde a Craudete compartilha as receitas da fam\u00edlia.<\/li>\n<li>Dinheiro: Local onde s\u00e3o compartilhadas dicas financeiras.<\/li>\n<li>Fam\u00edlia e Relacionamentos: A ess\u00eancia do Canal Brancoala tamb\u00e9m tem uma sess\u00e3o dedicada pra ela.<\/li>\n<\/ul>\n<p><strong>\u2022 Livro:<\/strong> Lan\u00e7ado em 2022, o livro \u201cBrancoala e Fam\u00edlia\u201d fala sobre como cada um precisa encontrar o seu prop\u00f3sito e guiar os sonhos a partir dele; apresentando como exemplo toda a hist\u00f3ria do relacionamento e da fam\u00edlia de Branco e Cl\u00e1udia.<\/p>\n<p><em>Isso \u00e9 que podemos chamar de \u201cexpandir a marca\u201d, n\u00e9?<\/em><\/p>\n<h2 class=\"wp-block-heading\">Parceria Brancoala e Animativa<\/h2>\n<p>Com todo esse sucesso, a gente n\u00e3o poderia deixar de convocar o Brancoala para o <a href=\"https:\/\/www.animativa.com\/br\/blog\/animativa-personagens-favoritos-estao-aqui\/\">time Animativa<\/a>, n\u00e9. Descubra nossos <a href=\"https:\/\/loja.animativa.com\/?utm_source=blog&amp;utm_medium=post&amp;utm_campaign=blog2store&amp;utm_content=canal-brancoala\" target=\"_blank\" rel=\"noopener\">produtos licenciados<\/a>!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quando pensamos nos famigerados \u201ccases de sucesso\u201d, surgem sempre as mesmas hist\u00f3rias repetidas e recheadas de clich\u00eas. N\u00e3o \u00e9 t\u00e3o f\u00e1cil encontrar um modelo de neg\u00f3cio verdadeiramente disruptor e que deu certo de verdade. Uma dessas exce\u00e7\u00f5es \u00e9 o Canal Brancoala, no Youtube. Branco, o idealizador do canal, posta de segunda a sexta-feira v\u00eddeos compartilhando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30625,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"class_list":["post-30624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades-e-criatividade"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/posts\/30624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/comments?post=30624"}],"version-history":[{"count":0,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/posts\/30624\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media\/30625"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/media?parent=30624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categories?post=30624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/tags?post=30624"},{"taxonomy":"categories","embeddable":true,"href":"https:\/\/dev.animativa.com\/pt-br\/wp-json\/wp\/v2\/categories?post=30624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}