{"id":30080,"date":"2024-03-28T19:32:56","date_gmt":"2024-03-28T22:32:56","guid":{"rendered":"https:\/\/dev.animativa.com\/?page_id=30080"},"modified":"2024-09-10T16:34:30","modified_gmt":"2024-09-10T19:34:30","slug":"esg","status":"publish","type":"page","link":"https:\/\/dev.animativa.com\/es\/esg\/","title":{"rendered":"ESG"},"content":{"rendered":"  \n  <script>\n    const ESG_COMMITMENT_CARDS = [{\"image\":{\"ID\":19879,\"id\":19879,\"title\":\"imagem\",\"filename\":\"imagem-11.png\",\"filesize\":6013,\"url\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"link\":\"https:\\\/\\\/dev.animativa.com\\\/es\\\/esg\\\/imagem-12-2\\\/\",\"alt\":\"\",\"author\":\"1\",\"description\":\"\",\"caption\":\"\",\"name\":\"imagem-12-2\",\"status\":\"inherit\",\"uploaded_to\":30080,\"date\":\"2024-04-01 13:34:54\",\"modified\":\"2024-09-10 19:14:13\",\"menu_order\":0,\"mime_type\":\"image\\\/png\",\"type\":\"image\",\"subtype\":\"png\",\"icon\":\"https:\\\/\\\/dev.animativa.com\\\/wp-includes\\\/images\\\/media\\\/default.png\",\"width\":400,\"height\":144,\"sizes\":{\"thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11-150x144.png\",\"thumbnail-width\":150,\"thumbnail-height\":144,\"medium\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11-300x108.png\",\"medium-width\":300,\"medium-height\":108,\"medium_large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"medium_large-width\":400,\"medium_large-height\":144,\"large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"large-width\":400,\"large-height\":144,\"1536x1536\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"1536x1536-width\":400,\"1536x1536-height\":144,\"2048x2048\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"2048x2048-width\":400,\"2048x2048-height\":144,\"thumb_600x600\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"thumb_600x600-width\":400,\"thumb_600x600-height\":144,\"thumb_376x650\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"thumb_376x650-width\":376,\"thumb_376x650-height\":135,\"thumb_600x361\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"thumb_600x361-width\":400,\"thumb_600x361-height\":144,\"thumb_small_210x192\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"thumb_small_210x192-width\":210,\"thumb_small_210x192-height\":76,\"thumb_medium_500x512\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"thumb_medium_500x512-width\":400,\"thumb_medium_500x512-height\":144,\"thumb_big_564x432\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"thumb_big_564x432-width\":400,\"thumb_big_564x432-height\":144,\"web-stories-poster-portrait\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"web-stories-poster-portrait-width\":400,\"web-stories-poster-portrait-height\":144,\"web-stories-publisher-logo\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"web-stories-publisher-logo-width\":96,\"web-stories-publisher-logo-height\":35,\"web-stories-thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-11.png\",\"web-stories-thumbnail-width\":150,\"web-stories-thumbnail-height\":54}},\"title\":\"ALMA - Academia Libre y M\\u00fasica y Arte\",\"law\":\"Ley de Incentivo a la Cultura\",\"city\":\"Ribeir\\u00e3o Preto\",\"text\":\"<p>El proyecto es una iniciativa promovida por la Asociaci\\u00f3n ALMA, una entidad privada sin fines lucrativos. El objetivo principal es promover el desarrollo t\\u00e9cnico y art\\u00edstico de ni\\u00f1os y adolescentes que est\\u00e9n ingresando en el universo de las artes, con \\u00e9nfasis especial en la m\\u00fasica.<br \\\/>\\nNuestra alianza con la organizaci\\u00f3n consiste en proveer soporte y recursos para crear un ambiente propicio al aprendizaje. Juntos, buscamos ofrecer oportunidades que estimulen la creatividad, la expresi\\u00f3n individual y el crecimiento personal de los participantes. Nos comprometemos a capacitar a los j\\u00f3venes para que exploren plenamente su potencial art\\u00edstico y musical, permiti\\u00e9ndoles seguir un camino significativo en el mundo de las artes.<\\\/p>\\n\",\"gallery\":[{\"ID\":19891,\"id\":19891,\"title\":\"atom-photo\",\"filename\":\"atom-photo-19.png\",\"filesize\":211858,\"url\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"link\":\"https:\\\/\\\/dev.animativa.com\\\/es\\\/atom-photo-20-2\\\/\",\"alt\":\"\",\"author\":\"1\",\"description\":\"\",\"caption\":\"\",\"name\":\"atom-photo-20-2\",\"status\":\"inherit\",\"uploaded_to\":0,\"date\":\"2024-04-01 15:10:07\",\"modified\":\"2024-09-11 14:14:44\",\"menu_order\":0,\"mime_type\":\"image\\\/png\",\"type\":\"image\",\"subtype\":\"png\",\"icon\":\"https:\\\/\\\/dev.animativa.com\\\/wp-includes\\\/images\\\/media\\\/default.png\",\"width\":501,\"height\":240,\"sizes\":{\"thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19-150x150.png\",\"thumbnail-width\":150,\"thumbnail-height\":150,\"medium\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19-300x144.png\",\"medium-width\":300,\"medium-height\":144,\"medium_large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"medium_large-width\":501,\"medium_large-height\":240,\"large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"large-width\":501,\"large-height\":240,\"1536x1536\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"1536x1536-width\":501,\"1536x1536-height\":240,\"2048x2048\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"2048x2048-width\":501,\"2048x2048-height\":240,\"thumb_600x600\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"thumb_600x600-width\":501,\"thumb_600x600-height\":240,\"thumb_376x650\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"thumb_376x650-width\":376,\"thumb_376x650-height\":180,\"thumb_600x361\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"thumb_600x361-width\":501,\"thumb_600x361-height\":240,\"thumb_small_210x192\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"thumb_small_210x192-width\":210,\"thumb_small_210x192-height\":101,\"thumb_medium_500x512\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"thumb_medium_500x512-width\":500,\"thumb_medium_500x512-height\":240,\"thumb_big_564x432\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"thumb_big_564x432-width\":501,\"thumb_big_564x432-height\":240,\"web-stories-poster-portrait\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"web-stories-poster-portrait-width\":501,\"web-stories-poster-portrait-height\":240,\"web-stories-publisher-logo\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"web-stories-publisher-logo-width\":96,\"web-stories-publisher-logo-height\":46,\"web-stories-thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/atom-photo-19.png\",\"web-stories-thumbnail-width\":150,\"web-stories-thumbnail-height\":72}},{\"ID\":19893,\"id\":19893,\"title\":\"imagem\",\"filename\":\"imagem-12.png\",\"filesize\":175383,\"url\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"link\":\"https:\\\/\\\/dev.animativa.com\\\/es\\\/imagem-13-2\\\/\",\"alt\":\"\",\"author\":\"1\",\"description\":\"\",\"caption\":\"\",\"name\":\"imagem-13-2\",\"status\":\"inherit\",\"uploaded_to\":0,\"date\":\"2024-04-01 15:10:40\",\"modified\":\"2024-09-11 14:14:59\",\"menu_order\":0,\"mime_type\":\"image\\\/png\",\"type\":\"image\",\"subtype\":\"png\",\"icon\":\"https:\\\/\\\/dev.animativa.com\\\/wp-includes\\\/images\\\/media\\\/default.png\",\"width\":501,\"height\":240,\"sizes\":{\"thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12-150x150.png\",\"thumbnail-width\":150,\"thumbnail-height\":150,\"medium\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12-300x144.png\",\"medium-width\":300,\"medium-height\":144,\"medium_large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"medium_large-width\":501,\"medium_large-height\":240,\"large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"large-width\":501,\"large-height\":240,\"1536x1536\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"1536x1536-width\":501,\"1536x1536-height\":240,\"2048x2048\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"2048x2048-width\":501,\"2048x2048-height\":240,\"thumb_600x600\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"thumb_600x600-width\":501,\"thumb_600x600-height\":240,\"thumb_376x650\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"thumb_376x650-width\":376,\"thumb_376x650-height\":180,\"thumb_600x361\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"thumb_600x361-width\":501,\"thumb_600x361-height\":240,\"thumb_small_210x192\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"thumb_small_210x192-width\":210,\"thumb_small_210x192-height\":101,\"thumb_medium_500x512\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"thumb_medium_500x512-width\":500,\"thumb_medium_500x512-height\":240,\"thumb_big_564x432\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"thumb_big_564x432-width\":501,\"thumb_big_564x432-height\":240,\"web-stories-poster-portrait\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"web-stories-poster-portrait-width\":501,\"web-stories-poster-portrait-height\":240,\"web-stories-publisher-logo\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"web-stories-publisher-logo-width\":96,\"web-stories-publisher-logo-height\":46,\"web-stories-thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/imagem-12.png\",\"web-stories-thumbnail-width\":150,\"web-stories-thumbnail-height\":72}}]},{\"image\":{\"ID\":19889,\"id\":19889,\"title\":\"cuidar\",\"filename\":\"cuidar.png\",\"filesize\":3657,\"url\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"link\":\"https:\\\/\\\/dev.animativa.com\\\/es\\\/esg\\\/cuidar-2\\\/\",\"alt\":\"\",\"author\":\"1\",\"description\":\"\",\"caption\":\"\",\"name\":\"cuidar-2\",\"status\":\"inherit\",\"uploaded_to\":30080,\"date\":\"2024-04-01 13:39:01\",\"modified\":\"2024-09-10 19:14:13\",\"menu_order\":0,\"mime_type\":\"image\\\/png\",\"type\":\"image\",\"subtype\":\"png\",\"icon\":\"https:\\\/\\\/dev.animativa.com\\\/wp-includes\\\/images\\\/media\\\/default.png\",\"width\":400,\"height\":144,\"sizes\":{\"thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar-150x144.png\",\"thumbnail-width\":150,\"thumbnail-height\":144,\"medium\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar-300x108.png\",\"medium-width\":300,\"medium-height\":108,\"medium_large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"medium_large-width\":400,\"medium_large-height\":144,\"large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"large-width\":400,\"large-height\":144,\"1536x1536\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"1536x1536-width\":400,\"1536x1536-height\":144,\"2048x2048\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"2048x2048-width\":400,\"2048x2048-height\":144,\"thumb_600x600\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"thumb_600x600-width\":400,\"thumb_600x600-height\":144,\"thumb_376x650\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"thumb_376x650-width\":376,\"thumb_376x650-height\":135,\"thumb_600x361\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"thumb_600x361-width\":400,\"thumb_600x361-height\":144,\"thumb_small_210x192\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"thumb_small_210x192-width\":210,\"thumb_small_210x192-height\":76,\"thumb_medium_500x512\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"thumb_medium_500x512-width\":400,\"thumb_medium_500x512-height\":144,\"thumb_big_564x432\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"thumb_big_564x432-width\":400,\"thumb_big_564x432-height\":144,\"web-stories-poster-portrait\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"web-stories-poster-portrait-width\":400,\"web-stories-poster-portrait-height\":144,\"web-stories-publisher-logo\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"web-stories-publisher-logo-width\":96,\"web-stories-publisher-logo-height\":35,\"web-stories-thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cuidar.png\",\"web-stories-thumbnail-width\":150,\"web-stories-thumbnail-height\":54}},\"title\":\"Cuidar HCB - Hospital de Amor\",\"law\":\"FUMCAD\",\"city\":\"Barretos\",\"text\":\"<p>El proyecto Cuidar HCB tiene el objetivo de hacerse cargo del costo para el tratamiento, prevenci\\u00f3n e investigaci\\u00f3n del c\\u00e1ncer infanto-juvenil, ya que los costos subsidiados por SUS no son suficientes para ofrecer una atenci\\u00f3n excelente a la poblaci\\u00f3n necesitada. Actualmente, el 70% de los ni\\u00f1os con c\\u00e1ncer pueden ser curadas, cuando son diagnosticadas de modo precoz y son atendidas en centros especializados. La mayor\\u00eda de estos ni\\u00f1os tendr\\u00e1 una vida normal tras el tratamiento.<br \\\/>\\nEl Hospital Infanto-juvenil, inaugurado el 24 de marzo de 2012, atiende ni\\u00f1os y adolescentes provenientes de los 26 Estados y el Distrito Federal. El edificio tiene estructuras innovadoras Facilitar, dinamizar y hacer m\\u00e1s agradable la interacci\\u00f3n de los ni\\u00f1os y sus familias en el ambiente hospitalario.<br \\\/>\\nEl Hospital cuenta con ambulatorio, salas de infusi\\u00f3n separadas por grupo de edad, centro de quimioterapia, laboratorio de emergencia, pronta atenci\\u00f3n 24 horas, centro quir\\u00fargico y CTI.<\\\/p>\\n\",\"gallery\":false},{\"image\":{\"ID\":19887,\"id\":19887,\"title\":\"guia\",\"filename\":\"guia.png\",\"filesize\":5841,\"url\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"link\":\"https:\\\/\\\/dev.animativa.com\\\/es\\\/esg\\\/guia-2\\\/\",\"alt\":\"\",\"author\":\"1\",\"description\":\"\",\"caption\":\"\",\"name\":\"guia-2\",\"status\":\"inherit\",\"uploaded_to\":30080,\"date\":\"2024-04-01 13:39:01\",\"modified\":\"2024-09-10 19:14:13\",\"menu_order\":0,\"mime_type\":\"image\\\/png\",\"type\":\"image\",\"subtype\":\"png\",\"icon\":\"https:\\\/\\\/dev.animativa.com\\\/wp-includes\\\/images\\\/media\\\/default.png\",\"width\":400,\"height\":144,\"sizes\":{\"thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia-150x144.png\",\"thumbnail-width\":150,\"thumbnail-height\":144,\"medium\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia-300x108.png\",\"medium-width\":300,\"medium-height\":108,\"medium_large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"medium_large-width\":400,\"medium_large-height\":144,\"large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"large-width\":400,\"large-height\":144,\"1536x1536\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"1536x1536-width\":400,\"1536x1536-height\":144,\"2048x2048\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"2048x2048-width\":400,\"2048x2048-height\":144,\"thumb_600x600\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"thumb_600x600-width\":400,\"thumb_600x600-height\":144,\"thumb_376x650\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"thumb_376x650-width\":376,\"thumb_376x650-height\":135,\"thumb_600x361\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"thumb_600x361-width\":400,\"thumb_600x361-height\":144,\"thumb_small_210x192\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"thumb_small_210x192-width\":210,\"thumb_small_210x192-height\":76,\"thumb_medium_500x512\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"thumb_medium_500x512-width\":400,\"thumb_medium_500x512-height\":144,\"thumb_big_564x432\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"thumb_big_564x432-width\":400,\"thumb_big_564x432-height\":144,\"web-stories-poster-portrait\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"web-stories-poster-portrait-width\":400,\"web-stories-poster-portrait-height\":144,\"web-stories-publisher-logo\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"web-stories-publisher-logo-width\":96,\"web-stories-publisher-logo-height\":35,\"web-stories-thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/guia.png\",\"web-stories-thumbnail-width\":150,\"web-stories-thumbnail-height\":54}},\"title\":\"GU\\u00cdA RP\",\"law\":\"Deportes\",\"city\":\"S\\u00e3o Jos\\u00e9 do Rio Preto\",\"text\":\"<p>La Gu\\u00eda RP es una organizaci\\u00f3n sin fines lucrativos que busca mejorar la calidad de vida y crear oportunidades iguales para todos por medio de un deporte que amamos: el voleibol. El proyecto usa el voleibol como herramienta motivadora de la acci\\u00f3n educativa para centenas de ni\\u00f1os y adolescentes de 10 y 17 a\\u00f1os, de varios or\\u00edgenes y niveles socio-econ\\u00f3micos y culturales, en situaci\\u00f3n de vulnerabilidad social del municipio de S\\u00e3o Jos\\u00e9 do Rio Preto y regi\\u00f3n.<br \\\/>\\nGracias a una alianza de cesi\\u00f3n gratuita de los espacios para deportes, las clases de la ONG GUIA RP se realizan de lunes a viernes, de 19h a 21h en la Escuela SEB. Direcci\\u00f3n \\u2013 Rua: Siqueira Campos, n\\u00ba 2552 \\u2013 Barrio Boa Vista. C\\u00f3digo Postal: 15025-055 S\\u00e3o Jos\\u00e9 do Rio Preto \\u2013 SP\\\/ Tel: +55 (17) 3303.4586.<\\\/p>\\n\",\"gallery\":false},{\"image\":{\"ID\":19885,\"id\":19885,\"title\":\"pequenos\",\"filename\":\"pequenos.png\",\"filesize\":10908,\"url\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"link\":\"https:\\\/\\\/dev.animativa.com\\\/es\\\/esg\\\/pequenos-2\\\/\",\"alt\":\"\",\"author\":\"1\",\"description\":\"\",\"caption\":\"\",\"name\":\"pequenos-2\",\"status\":\"inherit\",\"uploaded_to\":30080,\"date\":\"2024-04-01 13:39:01\",\"modified\":\"2024-09-10 19:14:13\",\"menu_order\":0,\"mime_type\":\"image\\\/png\",\"type\":\"image\",\"subtype\":\"png\",\"icon\":\"https:\\\/\\\/dev.animativa.com\\\/wp-includes\\\/images\\\/media\\\/default.png\",\"width\":400,\"height\":144,\"sizes\":{\"thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos-150x144.png\",\"thumbnail-width\":150,\"thumbnail-height\":144,\"medium\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos-300x108.png\",\"medium-width\":300,\"medium-height\":108,\"medium_large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"medium_large-width\":400,\"medium_large-height\":144,\"large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"large-width\":400,\"large-height\":144,\"1536x1536\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"1536x1536-width\":400,\"1536x1536-height\":144,\"2048x2048\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"2048x2048-width\":400,\"2048x2048-height\":144,\"thumb_600x600\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"thumb_600x600-width\":400,\"thumb_600x600-height\":144,\"thumb_376x650\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"thumb_376x650-width\":376,\"thumb_376x650-height\":135,\"thumb_600x361\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"thumb_600x361-width\":400,\"thumb_600x361-height\":144,\"thumb_small_210x192\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"thumb_small_210x192-width\":210,\"thumb_small_210x192-height\":76,\"thumb_medium_500x512\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"thumb_medium_500x512-width\":400,\"thumb_medium_500x512-height\":144,\"thumb_big_564x432\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"thumb_big_564x432-width\":400,\"thumb_big_564x432-height\":144,\"web-stories-poster-portrait\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"web-stories-poster-portrait-width\":400,\"web-stories-poster-portrait-height\":144,\"web-stories-publisher-logo\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"web-stories-publisher-logo-width\":96,\"web-stories-publisher-logo-height\":35,\"web-stories-thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/pequenos.png\",\"web-stories-thumbnail-width\":150,\"web-stories-thumbnail-height\":54}},\"title\":\"Peque\\u00f1os Grandes Lectores\",\"law\":\"Ley de Incentivo a la Cultura\",\"city\":\"S\\u00e3o Paulo\",\"text\":\"<p>El proyecto Peque\\u00f1os Grandes Lectores busca implementar, en comunidades escolares, hospitales y otras instituciones, una biblioteca infantil con acervo de libros, juguetes, juegos y muebles que tienen el objetivo de estimular la lectura y los juego a los ni\\u00f1o de cero a ocho a\\u00f1os. Adem\\u00e1s del acervo con 400 libros infantiles, que incluyen diferentes tipos de narrativas, g\\u00e9neros, temas y obras, est\\u00e1n disponibles cerca de 20 libros destinados a la formaci\\u00f3n de educadores.<\\\/p>\\n\",\"gallery\":false},{\"image\":{\"ID\":19883,\"id\":19883,\"title\":\"recanto\",\"filename\":\"recanto.png\",\"filesize\":10828,\"url\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"link\":\"https:\\\/\\\/dev.animativa.com\\\/es\\\/esg\\\/recanto-2\\\/\",\"alt\":\"\",\"author\":\"1\",\"description\":\"\",\"caption\":\"\",\"name\":\"recanto-2\",\"status\":\"inherit\",\"uploaded_to\":30080,\"date\":\"2024-04-01 13:39:01\",\"modified\":\"2024-09-10 19:14:13\",\"menu_order\":0,\"mime_type\":\"image\\\/png\",\"type\":\"image\",\"subtype\":\"png\",\"icon\":\"https:\\\/\\\/dev.animativa.com\\\/wp-includes\\\/images\\\/media\\\/default.png\",\"width\":400,\"height\":144,\"sizes\":{\"thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto-150x144.png\",\"thumbnail-width\":150,\"thumbnail-height\":144,\"medium\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto-300x108.png\",\"medium-width\":300,\"medium-height\":108,\"medium_large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"medium_large-width\":400,\"medium_large-height\":144,\"large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"large-width\":400,\"large-height\":144,\"1536x1536\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"1536x1536-width\":400,\"1536x1536-height\":144,\"2048x2048\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"2048x2048-width\":400,\"2048x2048-height\":144,\"thumb_600x600\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"thumb_600x600-width\":400,\"thumb_600x600-height\":144,\"thumb_376x650\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"thumb_376x650-width\":376,\"thumb_376x650-height\":135,\"thumb_600x361\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"thumb_600x361-width\":400,\"thumb_600x361-height\":144,\"thumb_small_210x192\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"thumb_small_210x192-width\":210,\"thumb_small_210x192-height\":76,\"thumb_medium_500x512\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"thumb_medium_500x512-width\":400,\"thumb_medium_500x512-height\":144,\"thumb_big_564x432\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"thumb_big_564x432-width\":400,\"thumb_big_564x432-height\":144,\"web-stories-poster-portrait\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"web-stories-poster-portrait-width\":400,\"web-stories-poster-portrait-height\":144,\"web-stories-publisher-logo\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"web-stories-publisher-logo-width\":96,\"web-stories-publisher-logo-height\":35,\"web-stories-thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/recanto.png\",\"web-stories-thumbnail-width\":150,\"web-stories-thumbnail-height\":54}},\"title\":\"Recanto Monsenhor Albino\",\"law\":\"Personas mayores\",\"city\":\"Catanduva\",\"text\":\"<p>Totalmente capaz de acoger a personas mayores de ambos sexos, de 60 a\\u00f1os o m\\u00e1s, el Recanto Monsenhor Albino les ofrece cuidados y atenci\\u00f3n integral, para las necesidades de habitaci\\u00f3n, alimentaci\\u00f3n, salud y convivencia social y familiar, adem\\u00e1s de desarrollar actividades buscando la integraci\\u00f3n de las personas mayores entre s\\u00ed y con la sociedad para que permanezcan activos y participantes dentro de la comunidad.<\\\/p>\\n\",\"gallery\":false},{\"image\":{\"ID\":19881,\"id\":19881,\"title\":\"toque\",\"filename\":\"toque.png\",\"filesize\":21466,\"url\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"link\":\"https:\\\/\\\/dev.animativa.com\\\/es\\\/esg\\\/toque-2\\\/\",\"alt\":\"\",\"author\":\"1\",\"description\":\"\",\"caption\":\"\",\"name\":\"toque-2\",\"status\":\"inherit\",\"uploaded_to\":30080,\"date\":\"2024-04-01 13:39:01\",\"modified\":\"2024-09-10 19:14:13\",\"menu_order\":0,\"mime_type\":\"image\\\/png\",\"type\":\"image\",\"subtype\":\"png\",\"icon\":\"https:\\\/\\\/dev.animativa.com\\\/wp-includes\\\/images\\\/media\\\/default.png\",\"width\":400,\"height\":144,\"sizes\":{\"thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque-150x144.png\",\"thumbnail-width\":150,\"thumbnail-height\":144,\"medium\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque-300x108.png\",\"medium-width\":300,\"medium-height\":108,\"medium_large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"medium_large-width\":400,\"medium_large-height\":144,\"large\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"large-width\":400,\"large-height\":144,\"1536x1536\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"1536x1536-width\":400,\"1536x1536-height\":144,\"2048x2048\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"2048x2048-width\":400,\"2048x2048-height\":144,\"thumb_600x600\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"thumb_600x600-width\":400,\"thumb_600x600-height\":144,\"thumb_376x650\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"thumb_376x650-width\":376,\"thumb_376x650-height\":135,\"thumb_600x361\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"thumb_600x361-width\":400,\"thumb_600x361-height\":144,\"thumb_small_210x192\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"thumb_small_210x192-width\":210,\"thumb_small_210x192-height\":76,\"thumb_medium_500x512\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"thumb_medium_500x512-width\":400,\"thumb_medium_500x512-height\":144,\"thumb_big_564x432\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"thumb_big_564x432-width\":400,\"thumb_big_564x432-height\":144,\"web-stories-poster-portrait\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"web-stories-poster-portrait-width\":400,\"web-stories-poster-portrait-height\":144,\"web-stories-publisher-logo\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"web-stories-publisher-logo-width\":96,\"web-stories-publisher-logo-height\":35,\"web-stories-thumbnail\":\"https:\\\/\\\/dev.animativa.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/toque.png\",\"web-stories-thumbnail-width\":150,\"web-stories-thumbnail-height\":54}},\"title\":\"Toque que Salva Vidas\",\"law\":\"FUMCAD\",\"city\":\"Araraquara\",\"text\":\"<p>El proyecto, inicialmente presentado como \\u201cEl Hambre No Espera\\u201d, llevando el nombre de la campa\\u00f1a nacional de combate al hambre en Brasil que inspir\\u00f3 varios proyectos con este objetivo, ampli\\u00f3 y evolucion\\u00f3 para tener su propio nombre. As\\u00ed, con el nombre \\u201cToque que Salva Vidas\\u201d, el proyecto cre\\u00f3 forma e inici\\u00f3 sus actividades el d\\u00eda 1\\u00ba de diciembre de 2022. Con el establecimiento de los huertos, el proyecto sigue en actividad desde entonces.<br \\\/>\\nCon una poblaci\\u00f3n de aproximadamente 238.339 personas, as\\u00ed como lo restante del pa\\u00eds, la ciudad de Araraquara, en el interior de S\\u00e3o Paulo, tambi\\u00e9n enfrenta el desaf\\u00edo del combate al hambre. En este sentido, el proyecto \\u201cToque que Salva Vidas\\u201d, ejecutado en colaboraci\\u00f3n con la Fundaci\\u00f3n Toque y el colectivo social Agrogueto, que tiene el objetivo de desarrollar autosuficiencia alimentaria y econ\\u00f3mica en los alrededores de Araraquara.<\\\/p>\\n\",\"gallery\":false}];\n  <\/script>\n\n  <section class=\"esg-commitments\">\n    <div class=\"esg-commitments-area esg-commitments-area--0\">\n      <img decoding=\"async\" loading=\"lazy\" class=\"grafismo d-none d-md-block\" src=\"https:\/\/dev.animativa.com\/wp-content\/themes\/futurebrand\/img\/grafismos\/grafismos0-esg.svg\" alt=\"Grafismo\">\n      <div class=\"container\">\n        <div class=\"top\">\n          <span class=\"top__title\">ESG<\/span>\n          <h1 class=\"top__subtitle\">Conozca nuestras pr\u00e1cticas de ESG<\/h1>\n                      <div class=\"top__text\"><p>Pero\u2026 \u00bfqu\u00e9 es ESG?<\/p>\n<p>Son las acciones y pol\u00edticas que adoptan las empresas para garantizar procesos \u00e9ticos, sostenibles y responsables en sus ecosistemas.<br \/>\nConozca nuestros compromisos:<\/p>\n<\/div>\n                  <\/div>\n      <\/div>\n    <\/div>\n    <div class=\"esg-commitments-area esg-commitments-area--1\">\n      <img decoding=\"async\" loading=\"lazy\" class=\"grafismo d-none d-md-block\" src=\"https:\/\/dev.animativa.com\/wp-content\/themes\/futurebrand\/img\/grafismos\/grafismos1-esg.svg\" alt=\"Grafismo\">\n\n      <div class=\"container\">\n        <div class=\"content\">\n          <h2 class=\"content__title\" data-text=\"Compromisos sociales\" data-text-style=\"compRomisos sOiales\">\n            <span class=\"lowercase\">Comp<\/span><span class=\"uppercase\">r<\/span><span class=\"lowercase\">omisos<\/span><span class=\"uppercase\"> <\/span><span class=\"lowercase\">s<\/span><span class=\"uppercase\">o<\/span><span class=\"lowercase\">iales<\/span>          <\/h2>\n                      <div class=\"content__text\">\n              <p>Nosotros somos as\u00ed: creemos en una sociedad m\u00e1s justa y feliz, que valora la humanidad y el medio ambiente. En definitiva, somos apasionados por la constante evoluci\u00f3n y siempre ver el mundo por diferentes \u00e1ngulos.<br \/>\nTenemos el compromiso de ser ambiental y socialmente responsables. Por aqu\u00ed, este asunto es serio e inspira la innovaci\u00f3n, el compromiso y la colaboraci\u00f3n de todo nuestro ecosistema.<br \/>\nEs as\u00ed como usamos la creatividad en la vida todos los d\u00edas, incentivando a todo el mundo a inventar nuevas maneras de pensar para encontrar soluciones cada vez m\u00e1s conscientes.<br \/>\nColocamos intensidad e intenci\u00f3n en todo lo que hacemos. \u00bfQuiere ver?<\/p>\n            <\/div>\n                  <\/div>\n\n        <div class=\"cards\">\n                      <div class=\"cards__item\">\n                              <div class=\"cards__item--logo\">\n                  <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/03\/imagem-11.png\" alt=\"\">\n                <\/div>\n              \n              <div class=\"cards__item--content\">\n                <div class=\"d-flex flex-column\">\n                  <h3 class=\"title\">ALMA &#8211; Academia Libre y M\u00fasica y Arte<\/h3>\n                  <span class=\"law\"><b>Lei:<\/b> Ley de Incentivo a la Cultura<\/span>\n                  <span class=\"city\"><b>Cidade:<\/b> Ribeir\u00e3o Preto<\/span>\n                <\/div>\n\n                <button class=\"button\" data-index=\"0\">saiba mais<\/button>\n              <\/div>\n            <\/div>\n                      <div class=\"cards__item\">\n                              <div class=\"cards__item--logo\">\n                  <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/03\/cuidar.png\" alt=\"\">\n                <\/div>\n              \n              <div class=\"cards__item--content\">\n                <div class=\"d-flex flex-column\">\n                  <h3 class=\"title\">Cuidar HCB &#8211; Hospital de Amor<\/h3>\n                  <span class=\"law\"><b>Lei:<\/b> FUMCAD<\/span>\n                  <span class=\"city\"><b>Cidade:<\/b> Barretos<\/span>\n                <\/div>\n\n                <button class=\"button\" data-index=\"1\">saiba mais<\/button>\n              <\/div>\n            <\/div>\n                      <div class=\"cards__item\">\n                              <div class=\"cards__item--logo\">\n                  <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/03\/guia.png\" alt=\"\">\n                <\/div>\n              \n              <div class=\"cards__item--content\">\n                <div class=\"d-flex flex-column\">\n                  <h3 class=\"title\">GU\u00cdA RP<\/h3>\n                  <span class=\"law\"><b>Lei:<\/b> Deportes<\/span>\n                  <span class=\"city\"><b>Cidade:<\/b> S\u00e3o Jos\u00e9 do Rio Preto<\/span>\n                <\/div>\n\n                <button class=\"button\" data-index=\"2\">saiba mais<\/button>\n              <\/div>\n            <\/div>\n                      <div class=\"cards__item\">\n                              <div class=\"cards__item--logo\">\n                  <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/03\/pequenos.png\" alt=\"\">\n                <\/div>\n              \n              <div class=\"cards__item--content\">\n                <div class=\"d-flex flex-column\">\n                  <h3 class=\"title\">Peque\u00f1os Grandes Lectores<\/h3>\n                  <span class=\"law\"><b>Lei:<\/b> Ley de Incentivo a la Cultura<\/span>\n                  <span class=\"city\"><b>Cidade:<\/b> S\u00e3o Paulo<\/span>\n                <\/div>\n\n                <button class=\"button\" data-index=\"3\">saiba mais<\/button>\n              <\/div>\n            <\/div>\n                      <div class=\"cards__item\">\n                              <div class=\"cards__item--logo\">\n                  <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/03\/recanto.png\" alt=\"\">\n                <\/div>\n              \n              <div class=\"cards__item--content\">\n                <div class=\"d-flex flex-column\">\n                  <h3 class=\"title\">Recanto Monsenhor Albino<\/h3>\n                  <span class=\"law\"><b>Lei:<\/b> Personas mayores<\/span>\n                  <span class=\"city\"><b>Cidade:<\/b> Catanduva<\/span>\n                <\/div>\n\n                <button class=\"button\" data-index=\"4\">saiba mais<\/button>\n              <\/div>\n            <\/div>\n                      <div class=\"cards__item\">\n                              <div class=\"cards__item--logo\">\n                  <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/03\/toque.png\" alt=\"\">\n                <\/div>\n              \n              <div class=\"cards__item--content\">\n                <div class=\"d-flex flex-column\">\n                  <h3 class=\"title\">Toque que Salva Vidas<\/h3>\n                  <span class=\"law\"><b>Lei:<\/b> FUMCAD<\/span>\n                  <span class=\"city\"><b>Cidade:<\/b> Araraquara<\/span>\n                <\/div>\n\n                <button class=\"button\" data-index=\"5\">saiba mais<\/button>\n              <\/div>\n            <\/div>\n                  <\/div>\n      <\/div>\n    <\/div>\n  <\/section>\n\n  <div class=\"esg-cards-modal\">\n    <div class=\"esg-cards-modal__box\">\n      <nav class=\"close-nav\">\n        <svg class=\"close\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n          <path d=\"M17.6575 4.92888C18.048 4.53836 18.6812 4.53835 19.0717 4.92888C19.4622 5.3194 19.4622 5.95257 19.0717 6.34309L13.4148 12L19.0717 17.6568C19.4622 18.0473 19.4622 18.6805 19.0717 19.071C18.6812 19.4615 18.048 19.4615 17.6575 19.071L12.0006 13.4142L6.34384 19.071C6.33773 19.0771 6.33157 19.0831 6.32535 19.089C5.93358 19.4614 5.31404 19.4554 4.92962 19.071C4.63673 18.7781 4.5635 18.3487 4.70995 17.9876C4.75876 17.8672 4.83199 17.7544 4.92962 17.6568L10.5864 12L4.92962 6.34314C4.53909 5.95262 4.53909 5.31945 4.92962 4.92893C5.32014 4.5384 5.95331 4.5384 6.34383 4.92893L12.0006 10.5857L17.6575 4.92888Z\" fill=\"#692AE0\" \/>\n        <\/svg>\n      <\/nav>\n\n      <h4 class=\"title\" id=\"modalTitle\"><\/h4>\n\n      <div id=\"modal-carousel\" class=\"carousel\">\n\n      <\/div>\n\n      <span class=\"law\"><b>Lei:<\/b>\n        <p id=\"modalLaw\"><\/p>\n      <\/span>\n      <span class=\"city\"><b>Cidade:<\/b>\n        <p id=\"modalCity\"><\/p>\n      <\/span>\n      <div class=\"description\" id=\"modalDescription\"><\/div>\n    <\/div>\n  <\/div>\n\n\n\n\n  \n  <section class=\"esg-environment\">\n    <div class=\"esg-environment-hero\" style=\"background-image: url('https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/08\/meio-ambiente-bg.jpg')\">\n      <img decoding=\"async\" loading=\"lazy\" class=\"grafismo d-none d-md-block\" src=\"https:\/\/dev.animativa.com\/wp-content\/themes\/futurebrand\/img\/grafismos\/grafismos-0-environment-esg.svg\" alt=\"Grafismo\">\n      <div class=\"container\">\n        <div class=\"row row--0\">\n          <div class=\"col-12\">\n            <h2 class=\"title\" data-text=\"Medio ambiente\" data-text-style=\"mEio AmbiEnTe\">\n              <span class=\"lowercase\">M<\/span><span class=\"uppercase\">e<\/span><span class=\"lowercase\">io<\/span><span class=\"uppercase\"> a<\/span><span class=\"lowercase\">mbi<\/span><span class=\"uppercase\">e<\/span><span class=\"lowercase\">n<\/span><span class=\"uppercase\">t<\/span><span class=\"lowercase\">e<\/span>            <\/h2>\n                          <div class=\"text\"><p>Sabemos que cuidar del medio ambiente significa cuidar a nosotros mismos.<br \/>\nPor eso, hacemos nuestra parte promoviendo la responsabilidad ambiental en nuestros procesos,\u2028minimizando impactos e impulsando un futuro m\u00e1s sostenible.<\/p>\n<\/div>\n                      <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\n    <div class=\"container\">\n\n      <div class=\"row row--1\">\n                            <div class=\"col-12 col-xl-6 left-content\">\n                          <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/07\/fsc-logo-branco.png\" alt=\"Selo FSC\">\n                              <h3 data-text=\"Sello fsc\u00ae\" data-text-style=\"sello fsc\u00ae\"><span class=\"lowercase\">Sello<\/span><span class=\"uppercase\"> <\/span><span class=\"lowercase\">fsc\u00ae<\/span><\/h3>\n                                            <div class=\"text\"><p>Tenemos consciencia de la importancia de adoptar pr\u00e1cticas comerciales que minimizan el impacto ambiental y promueven la conservaci\u00f3n de los recursos naturales. Al obtener el sello FSC\u00ae para nuestros productos, aseguramos a los clientes y stakeholders que la materia prima utilizada proviene de bosques manejados de forma responsable y sostenible.<\/p>\n<p>Adem\u00e1s, el sello FSC\u00ae promueve pr\u00e1cticas sociales justas, garantizando condiciones de trabajo seguras y adecuadas para los trabajadores involucrados en la cadena de suministros. Esto no s\u00f3lo beneficia directamente a las personas involucradas en la producci\u00f3n, pero tambi\u00e9n contribuye con la construcci\u00f3n de comunidades m\u00e1s sostenibles e inclusivas.<\/p>\n<\/div>\n                                    <\/div>\n                            <div class=\"col-12 col-xl-6 right-content\">\n                          <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/06\/selo-horizontal-eu-reciclo-1.png\" alt=\"Selo FSC\">\n                              <h3 data-text=\"Yo reciclo\" data-text-style=\"yo Reciclo\"><span class=\"lowercase\">Yo<\/span><span class=\"uppercase\"> r<\/span><span class=\"lowercase\">eciclo<\/span><\/h3>\n                                            <div class=\"text\"><p>La sostenibilidad forma parte de nuestros objetivos y valoramos el futuro \u2013 para nosotros que estamos aqu\u00ed y para las pr\u00f3ximas generaciones.<br \/>\nPor eso, contamos con el sello Eureciclo (Yoreciclo) y contribuimos con el aumento del reciclaje en Brasil. S\u00f3lo en 2022, en colaboraci\u00f3n con la instituci\u00f3n, \u00a1reciclamos aproximadamente 8 mil kg de material!<br \/>\nConozca m\u00e1s sobre Eureciclo en:<br \/>\nhttps:\/\/lnkd.in\/eicfESh<\/p>\n<\/div>\n                                    <\/div>\n              <\/div>\n    <\/div>\n  <\/section>\n\n\n\n  \n  <section class=\"esg-governance\">\n    <div class=\"esg-governance-hero\" style=\"background-image: url('https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/08\/governanca-bg.jpg')\">\n      <img decoding=\"async\" loading=\"lazy\" class=\"grafismo d-none d-md-block\" src=\"https:\/\/dev.animativa.com\/wp-content\/themes\/futurebrand\/img\/grafismos\/grafismos-0-governance-esg.svg\" alt=\"Grafismo\">\n      <div class=\"container\">\n        <div class=\"row row--0\">\n          <div class=\"col-12 content\">\n            <h2 class=\"title\" data-text=\"Gobernanza\" data-text-style=\"gobErnanza\"><span class=\"lowercase\">Gob<\/span><span class=\"uppercase\">e<\/span><span class=\"lowercase\">rnanza<\/span><\/h2>\n                          <div class=\"text\"><p>Honestidad y transparencia son valores no negociables para nosotros. Nuestras pr\u00e1cticas de colaboraci\u00f3n son un ejemplo de c\u00f3mo construimos rutinas de trabajo seguras y relaciones de confianza. Tenemos el compromiso con la integridad, con la calidad de nuestros productos y con el mantenimiento de relaciones duraderas con nuestros clientes y aliados.<\/p>\n<\/div>\n                      <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n\n    <div class=\"container\">\n      <div class=\"row row--1\">\n        <div class=\"col-12\">\n                      <div class=\"text-secondary\"><p>Con un equipo especializado y gobernanza corporativa estructurada, desarrollamos pr\u00e1cticas de gesti\u00f3n ambidiestra para crecer cada vez m\u00e1s, y hacer la diferencia en el mercado \u2013 \u00a1y en la vida de todos los que se relacionan con nosotros!<\/p>\n<\/div>\n                  <\/div>\n        <div class=\"col-12 certifications\">\n          <div class=\"certifications__column\">\n                                        <div class=\"certifications__item\">\n                <div class=\"certifications__item--stamp\">\n                                      <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/07\/inmetro-logo-selo.png\" alt=\"\">\n                                  <\/div>\n\n                <div class=\"certifications__item--content\">\n                  <h3 class=\"title\">sello inmetro<\/h3>\n                                      <div class=\"description\"><p>La certificaci\u00f3n de Inmetro conquistada recientemente por nuestra empresa es un marco significativo en el compromiso de la organizaci\u00f3n con la calidad, seguridad y excelencia de nuestros productos.<\/p>\n<\/div>\n                                  <\/div>\n              <\/div>\n                                                      <div class=\"certifications__item\">\n                <div class=\"certifications__item--stamp\">\n                                      <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/03\/atom-photo-20.png\" alt=\"\">\n                                  <\/div>\n\n                <div class=\"certifications__item--content\">\n                  <h3 class=\"title\">sello disney fama<\/h3>\n                                      <div class=\"description\"><p>El sello Disney FAMA es obligatorio para la fabricaci\u00f3n de productos, componentes y materiales que tengan propiedad intelectual de la marca y requiere que estemos alineados a su c\u00f3digo de conducta y a las normas de la Organizaci\u00f3n Mundial del Trabajo (ILO). Este proceso refuerza nuestra responsabilidad en la producci\u00f3n de mercader\u00edas en conformidad con los elevados est\u00e1ndares establecidos por Disney.<\/p>\n<\/div>\n                                  <\/div>\n              <\/div>\n                                                      <div class=\"certifications__item\">\n                <div class=\"certifications__item--stamp\">\n                                  <\/div>\n\n                <div class=\"certifications__item--content\">\n                  <h3 class=\"title\">auditor\u00eda externa de gesti\u00f3n financiera<\/h3>\n                                      <div class=\"description\"><p>Colocamos nuestros valores de transparencia en pr\u00e1ctica por medio de auditor\u00edas externas en nuestros procesos. Esto asegura que nuestras operaciones est\u00e9n alineadas a los mejores est\u00e1ndares contables, normas y reglamentaciones, fortaleciendo, as\u00ed, la confianza de nuestros aliados y clientes.<\/p>\n<\/div>\n                                  <\/div>\n              <\/div>\n                                    <\/div>\n          <div class=\"certifications__column\">\n                                                      <div class=\"certifications__item\">\n                <div class=\"certifications__item--stamp\">\n                                      <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/07\/iso-logo-reduzido.png\" alt=\"\">\n                                  <\/div>\n\n                <div class=\"certifications__item--content\">\n                  <h3 class=\"title\">sellos iso 9001, iso 45001 e iso 14001<\/h3>\n                                      <div class=\"description\"><p>La certificaci\u00f3n ISO 9001 nos orienta a mantener un sistema de gesti\u00f3n de calidad eficaz, permitiendo que operemos de manera consistente, atendiendo a las expectativas de nuestros clientes y buscando mejoras constantemente.<\/p>\n<p>La certificaci\u00f3n ISO 45001, que refleja nuestro compromiso con la salud y seguridad ocupacional de nuestro equipo, establece los requisitos para un sistema de gesti\u00f3n de salud y seguridad en el trabajo, proporcionando un ambiente de trabajo seguro, previniendo lesiones y problemas de salud relacionados al trabajo.<\/p>\n<p>La obtenci\u00f3n de la certificaci\u00f3n ISO 14001 tambi\u00e9n es fundamental para nosotros, pues refleja nuestro compromiso con la preservaci\u00f3n de la naturaleza y nos ayuda a minimizar el impacto en el medio ambiente, controlando aspectos ambientales y promoviendo pr\u00e1cticas sostenibles en todas nuestras operaciones.<\/p>\n<\/div>\n                                  <\/div>\n              <\/div>\n                                                      <div class=\"certifications__item\">\n                <div class=\"certifications__item--stamp\">\n                                  <\/div>\n\n                <div class=\"certifications__item--content\">\n                  <h3 class=\"title\">compliance<\/h3>\n                                      <div class=\"description\"><p>Tenemos pol\u00edticas de compliance claras, que garantizan que todo nuestro equipo tenga apoyo para entender y cumplir los est\u00e1ndares \u00e9ticos y legales. A partir de controles internos, se ha hecho el monitoreo de posibles desv\u00edos para corregirlos lo m\u00e1s pronto posible. Un abordaje que no s\u00f3lo disminuye riesgos legales y de reputaci\u00f3n, como tambi\u00e9n fortalece la confianza de los steakholders, consolid\u00e1ndonos como una empresa comprometida con la excelencia y valores \u00edntegros en nuestras operaciones.<\/p>\n<\/div>\n                                  <\/div>\n              <\/div>\n                                                      <div class=\"certifications__item\">\n                <div class=\"certifications__item--stamp\">\n                                  <\/div>\n\n                <div class=\"certifications__item--content\">\n                  <h3 class=\"title\">canal de \u00e9tica <\/h3>\n                                      <div class=\"description\"><p>Contamos con un canal de \u00e9tica an\u00f3nimo y seguro, en el cual colaboradores, proveedores y aliados pueden relatar cualquier conducta irregular identificada en el ambiente de trabajo, como acoso, fraude y bullying, por ejemplo.<br \/>\nSon dos canales de atenci\u00f3n: por el sitio web www.contatoseguro.com.br\/animativa o al tel\u00e9fono 0800 517 1309.<\/p>\n<\/div>\n                                  <\/div>\n              <\/div>\n                      <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/section>\n\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"templates\/blocks.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-30080","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/es\/wp-json\/wp\/v2\/pages\/30080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.animativa.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/es\/wp-json\/wp\/v2\/comments?post=30080"}],"version-history":[{"count":3,"href":"https:\/\/dev.animativa.com\/es\/wp-json\/wp\/v2\/pages\/30080\/revisions"}],"predecessor-version":[{"id":30094,"href":"https:\/\/dev.animativa.com\/es\/wp-json\/wp\/v2\/pages\/30080\/revisions\/30094"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/es\/wp-json\/wp\/v2\/media?parent=30080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}