{"id":1076,"date":"2024-04-16T13:39:37","date_gmt":"2024-04-16T13:39:37","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-b\/"},"modified":"2024-04-16T13:39:37","modified_gmt":"2024-04-16T13:39:37","slug":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-b","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-b\/","title":{"rendered":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas &#8211; Capa B"},"author":1,"featured_media":1062,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[45],"produto_capa":[227],"produto_lombada":[238],"produto_tipo_folha":[248],"produto_folha":[296],"produto_gramatura":[300],"produto_formato_mm":[310],"produto_selo":[362],"produto_caracteristica":[392,393,409,401],"class_list":["post-1076","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-brochurao-cd-costurado-1-4","produto_capa-dura","produto_lombada-costurada","produto_tipo_folha-pautado","produto_folha-296","produto_gramatura-300","produto_formato_mm-140x200","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-cartela-de-adesivos-dupla","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca"],"acf":{"infos_produto":{"sku":"10485","ean":"7891321104859","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1075,1077,1078],"related_products":[{"id":1071,"date":"2024-04-16T13:38:39","date_gmt":"2024-04-16T13:38:39","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-80-folhas-capa-a\/"},"modified":"2024-05-22T14:37:12","modified_gmt":"2024-05-22T17:37:12","slug":"turma-da-monica-caderno-brochura-1-4-80-folhas-capa-a","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-caderno-brochura-1-4-80-folhas-capa-a\/","title":{"rendered":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 80 folhas &#8211; Capa A"},"author":1,"featured_media":14222,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[45],"produto_capa":[227],"produto_lombada":[238],"produto_tipo_folha":[248],"produto_folha":[267],"produto_gramatura":[300],"produto_formato_mm":[310],"produto_selo":[362],"produto_caracteristica":[392,393,409,401],"class_list":["post-1071","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-brochurao-cd-costurado-1-4","produto_capa-dura","produto_lombada-costurada","produto_tipo_folha-pautado","produto_folha-267","produto_gramatura-300","produto_formato_mm-140x200","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-cartela-de-adesivos-dupla","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca"],"acf":{"infos_produto":{"sku":"10486","ean":"7891321104866","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>\u00c9 hora de celebrar a magia da Turma da M\u00f4nica! Esses quadrinhos brasileiros, criados pelo lend\u00e1rio Maur\u00edcio de Sousa, s\u00e3o verdadeiros cl\u00e1ssicos que nunca saem de moda. Agora, voc\u00ea pode ter esses personagens ador\u00e1veis em sua cole\u00e7\u00e3o da Animativa, garantindo momentos de pura divers\u00e3o e muito amor!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1072,1073,1074],"related_products":[{"ID":1075,"post_author":"1","post_date":"2024-04-16 13:39:25","post_date_gmt":"2024-04-16 13:39:25","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa A","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-a","to_ping":"","pinged":"","post_modified":"2024-05-22 14:36:04","post_modified_gmt":"2024-05-22 17:36:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1076,"post_author":"1","post_date":"2024-04-16 13:39:37","post_date_gmt":"2024-04-16 13:39:37","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa B","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-b","to_ping":"","pinged":"","post_modified":"2024-04-16 13:39:37","post_modified_gmt":"2024-04-16 13:39:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1077,"post_author":"1","post_date":"2024-04-16 13:39:48","post_date_gmt":"2024-04-16 13:39:48","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa C","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-c","to_ping":"","pinged":"","post_modified":"2024-04-16 13:39:48","post_modified_gmt":"2024-04-16 13:39:48","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1078,"post_author":"1","post_date":"2024-04-16 13:40:00","post_date_gmt":"2024-04-16 13:40:00","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa D","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-d","to_ping":"","pinged":"","post_modified":"2024-04-16 13:40:00","post_modified_gmt":"2024-04-16 13:40:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"link_blog":"","link_marcas":"","caixa_master":"","atributos":"","images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMonica_2024-cost_1I1-capas-48f-1-1.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":238,"name":"Costurada","slug":"costurada"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":267,"name":"80","slug":"80"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":310,"name":"140x200","slug":"140x200"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1071\/revisions"}],"predecessor-version":[{"id":14224,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1071\/revisions\/14224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/14222"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1071"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1071"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1071"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1071"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1071"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1071"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1071"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1071"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1071"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":1072,"date":"2024-04-16T13:38:51","date_gmt":"2024-04-16T13:38:51","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-80-folhas-capa-b\/"},"modified":"2024-04-16T13:38:51","modified_gmt":"2024-04-16T13:38:51","slug":"turma-da-monica-caderno-brochura-1-4-80-folhas-capa-b","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-caderno-brochura-1-4-80-folhas-capa-b\/","title":{"rendered":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 80 folhas &#8211; Capa B"},"author":1,"featured_media":1062,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[45],"produto_capa":[227],"produto_lombada":[238],"produto_tipo_folha":[248],"produto_folha":[267],"produto_gramatura":[300],"produto_formato_mm":[310],"produto_selo":[362],"produto_caracteristica":[392,393,409,401],"class_list":["post-1072","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-brochurao-cd-costurado-1-4","produto_capa-dura","produto_lombada-costurada","produto_tipo_folha-pautado","produto_folha-267","produto_gramatura-300","produto_formato_mm-140x200","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-cartela-de-adesivos-dupla","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca"],"acf":{"infos_produto":{"sku":"10486","ean":"7891321104866","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>\u00c9 hora de celebrar a magia da Turma da M\u00f4nica! Esses quadrinhos brasileiros, criados pelo lend\u00e1rio Maur\u00edcio de Sousa, s\u00e3o verdadeiros cl\u00e1ssicos que nunca saem de moda. Agora, voc\u00ea pode ter esses personagens ador\u00e1veis em sua cole\u00e7\u00e3o da Animativa, garantindo momentos de pura divers\u00e3o e muito amor!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1071,1073,1074],"related_products":[{"ID":1075,"post_author":"1","post_date":"2024-04-16 13:39:25","post_date_gmt":"2024-04-16 13:39:25","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa A","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-a","to_ping":"","pinged":"","post_modified":"2024-05-22 14:36:04","post_modified_gmt":"2024-05-22 17:36:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1076,"post_author":"1","post_date":"2024-04-16 13:39:37","post_date_gmt":"2024-04-16 13:39:37","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa B","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-b","to_ping":"","pinged":"","post_modified":"2024-04-16 13:39:37","post_modified_gmt":"2024-04-16 13:39:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1077,"post_author":"1","post_date":"2024-04-16 13:39:48","post_date_gmt":"2024-04-16 13:39:48","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa C","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-c","to_ping":"","pinged":"","post_modified":"2024-04-16 13:39:48","post_modified_gmt":"2024-04-16 13:39:48","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1078,"post_author":"1","post_date":"2024-04-16 13:40:00","post_date_gmt":"2024-04-16 13:40:00","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa D","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-d","to_ping":"","pinged":"","post_modified":"2024-04-16 13:40:00","post_modified_gmt":"2024-04-16 13:40:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMonica_2024-cost_1I1-capas-48f-2.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":238,"name":"Costurada","slug":"costurada"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":267,"name":"80","slug":"80"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":310,"name":"140x200","slug":"140x200"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1072\/revisions"}],"predecessor-version":[{"id":2961,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1072\/revisions\/2961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/1062"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1072"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1072"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1072"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1072"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1072"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1072"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1072"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1072"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1072"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":1073,"date":"2024-04-16T13:39:02","date_gmt":"2024-04-16T13:39:02","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-80-folhas-capa-c\/"},"modified":"2024-04-16T13:39:02","modified_gmt":"2024-04-16T13:39:02","slug":"turma-da-monica-caderno-brochura-1-4-80-folhas-capa-c","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-caderno-brochura-1-4-80-folhas-capa-c\/","title":{"rendered":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 80 folhas &#8211; Capa C"},"author":1,"featured_media":1064,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[45],"produto_capa":[227],"produto_lombada":[238],"produto_tipo_folha":[248],"produto_folha":[267],"produto_gramatura":[300],"produto_formato_mm":[310],"produto_selo":[362],"produto_caracteristica":[392,393,409,401],"class_list":["post-1073","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-brochurao-cd-costurado-1-4","produto_capa-dura","produto_lombada-costurada","produto_tipo_folha-pautado","produto_folha-267","produto_gramatura-300","produto_formato_mm-140x200","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-cartela-de-adesivos-dupla","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca"],"acf":{"infos_produto":{"sku":"10486","ean":"7891321104866","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>\u00c9 hora de celebrar a magia da Turma da M\u00f4nica! Esses quadrinhos brasileiros, criados pelo lend\u00e1rio Maur\u00edcio de Sousa, s\u00e3o verdadeiros cl\u00e1ssicos que nunca saem de moda. Agora, voc\u00ea pode ter esses personagens ador\u00e1veis em sua cole\u00e7\u00e3o da Animativa, garantindo momentos de pura divers\u00e3o e muito amor!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1071,1072,1074],"related_products":[{"ID":1075,"post_author":"1","post_date":"2024-04-16 13:39:25","post_date_gmt":"2024-04-16 13:39:25","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa A","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-a","to_ping":"","pinged":"","post_modified":"2024-05-22 14:36:04","post_modified_gmt":"2024-05-22 17:36:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1076,"post_author":"1","post_date":"2024-04-16 13:39:37","post_date_gmt":"2024-04-16 13:39:37","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa B","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-b","to_ping":"","pinged":"","post_modified":"2024-04-16 13:39:37","post_modified_gmt":"2024-04-16 13:39:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1077,"post_author":"1","post_date":"2024-04-16 13:39:48","post_date_gmt":"2024-04-16 13:39:48","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa C","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-c","to_ping":"","pinged":"","post_modified":"2024-04-16 13:39:48","post_modified_gmt":"2024-04-16 13:39:48","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1078,"post_author":"1","post_date":"2024-04-16 13:40:00","post_date_gmt":"2024-04-16 13:40:00","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa D","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-d","to_ping":"","pinged":"","post_modified":"2024-04-16 13:40:00","post_modified_gmt":"2024-04-16 13:40:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMonica_2024-cost_1I1-capas-48f-3.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":238,"name":"Costurada","slug":"costurada"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":267,"name":"80","slug":"80"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":310,"name":"140x200","slug":"140x200"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1073\/revisions"}],"predecessor-version":[{"id":2962,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1073\/revisions\/2962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/1064"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1073"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1073"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1073"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1073"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1073"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1073"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1073"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1073"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1073"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":1074,"date":"2024-04-16T13:39:14","date_gmt":"2024-04-16T13:39:14","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-80-folhas-capa-d\/"},"modified":"2024-04-16T13:39:14","modified_gmt":"2024-04-16T13:39:14","slug":"turma-da-monica-caderno-brochura-1-4-80-folhas-capa-d","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-caderno-brochura-1-4-80-folhas-capa-d\/","title":{"rendered":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 80 folhas &#8211; Capa D"},"author":1,"featured_media":1066,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[45],"produto_capa":[227],"produto_lombada":[238],"produto_tipo_folha":[248],"produto_folha":[267],"produto_gramatura":[300],"produto_formato_mm":[310],"produto_selo":[362],"produto_caracteristica":[392,393,409,401],"class_list":["post-1074","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-brochurao-cd-costurado-1-4","produto_capa-dura","produto_lombada-costurada","produto_tipo_folha-pautado","produto_folha-267","produto_gramatura-300","produto_formato_mm-140x200","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-cartela-de-adesivos-dupla","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca"],"acf":{"infos_produto":{"sku":"10486","ean":"7891321104866","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>\u00c9 hora de celebrar a magia da Turma da M\u00f4nica! Esses quadrinhos brasileiros, criados pelo lend\u00e1rio Maur\u00edcio de Sousa, s\u00e3o verdadeiros cl\u00e1ssicos que nunca saem de moda. Agora, voc\u00ea pode ter esses personagens ador\u00e1veis em sua cole\u00e7\u00e3o da Animativa, garantindo momentos de pura divers\u00e3o e muito amor!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1071,1072,1073],"related_products":[{"ID":1075,"post_author":"1","post_date":"2024-04-16 13:39:25","post_date_gmt":"2024-04-16 13:39:25","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa A","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-a","to_ping":"","pinged":"","post_modified":"2024-05-22 14:36:04","post_modified_gmt":"2024-05-22 17:36:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1076,"post_author":"1","post_date":"2024-04-16 13:39:37","post_date_gmt":"2024-04-16 13:39:37","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa B","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-b","to_ping":"","pinged":"","post_modified":"2024-04-16 13:39:37","post_modified_gmt":"2024-04-16 13:39:37","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1077,"post_author":"1","post_date":"2024-04-16 13:39:48","post_date_gmt":"2024-04-16 13:39:48","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa C","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-c","to_ping":"","pinged":"","post_modified":"2024-04-16 13:39:48","post_modified_gmt":"2024-04-16 13:39:48","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1078,"post_author":"1","post_date":"2024-04-16 13:40:00","post_date_gmt":"2024-04-16 13:40:00","post_content":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/4- 48 folhas - Capa D","post_excerpt":"Reviva a nostalgia e a alegria com a Turma da M\u00f4nica! Criada por Maur\u00edcio de Sousa em 1959, essa s\u00e9rie de quadrinhos \u00e9 um verdadeiro tesouro nacional que continua encantando pessoas de todas as idades. Agora, voc\u00ea pode trazer toda essa divers\u00e3o e amor para sua cole\u00e7\u00e3o da Animativa, com os personagens mais queridos do Brasil!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-4-48-folhas-capa-d","to_ping":"","pinged":"","post_modified":"2024-04-16 13:40:00","post_modified_gmt":"2024-04-16 13:40:00","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-4-48-folhas-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMonica_2024-cost_1I1-capas-48f-4.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":238,"name":"Costurada","slug":"costurada"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":267,"name":"80","slug":"80"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":310,"name":"140x200","slug":"140x200"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1074\/revisions"}],"predecessor-version":[{"id":2963,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1074\/revisions\/2963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/1066"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1074"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1074"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1074"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1074"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1074"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1074"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1074"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1074"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1074"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMonica_2024-cost_1I1-capas-48f-2.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":238,"name":"Costurada","slug":"costurada"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":296,"name":"48","slug":"48"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":310,"name":"140x200","slug":"140x200"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1076\/revisions"}],"predecessor-version":[{"id":2965,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1076\/revisions\/2965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/1062"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1076"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1076"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1076"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1076"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1076"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1076"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1076"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1076"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1076"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}