{"id":1067,"date":"2024-04-16T13:37:52","date_gmt":"2024-04-16T13:37:52","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-a\/"},"modified":"2024-04-16T13:37:52","modified_gmt":"2024-04-16T13:37:52","slug":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-a","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-a\/","title":{"rendered":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas &#8211; Capa A"},"author":1,"featured_media":4490,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[38],"produto_capa":[227],"produto_lombada":[238],"produto_tipo_folha":[248],"produto_folha":[296],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,393,409,401],"class_list":["post-1067","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-brochurao-cd-costurado-1-1","produto_capa-dura","produto_lombada-costurada","produto_tipo_folha-pautado","produto_folha-296","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-cartela-de-adesivos-dupla","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca"],"acf":{"infos_produto":{"sku":"10452","ean":"7891321104521","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1068,1069,1070],"related_products":[{"id":1058,"date":"2024-04-16T13:37:06","date_gmt":"2024-04-16T13:37:06","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-80-folhas-capa-a\/"},"modified":"2024-04-16T13:37:06","modified_gmt":"2024-04-16T13:37:06","slug":"turma-da-monica-caderno-brochura-1-1-80-folhas-capa-a","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-caderno-brochura-1-1-80-folhas-capa-a\/","title":{"rendered":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 80 folhas &#8211; Capa A"},"author":1,"featured_media":4490,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[38],"produto_capa":[227],"produto_lombada":[238],"produto_tipo_folha":[248],"produto_folha":[267],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,393,409,401],"class_list":["post-1058","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-brochurao-cd-costurado-1-1","produto_capa-dura","produto_lombada-costurada","produto_tipo_folha-pautado","produto_folha-267","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-cartela-de-adesivos-dupla","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca"],"acf":{"infos_produto":{"sku":"10429","ean":"7891321104293","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>A Turma da M\u00f4nica \u00e9 simplesmente imbat\u00edvel! Criada pelo talentoso Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira \u00e9 um verdadeiro tesouro nacional, amada por pessoas de todas as idades. E agora, voc\u00ea pode ter esses personagens incr\u00edveis em sua cole\u00e7\u00e3o da Animativa, garantindo momentos de pura divers\u00e3o e amor!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1061,1063,1065],"related_products":[{"ID":1067,"post_author":"1","post_date":"2024-04-16 13:37:52","post_date_gmt":"2024-04-16 13:37:52","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa A","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-a","to_ping":"","pinged":"","post_modified":"2024-04-16 13:37:52","post_modified_gmt":"2024-04-16 13:37:52","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1068,"post_author":"1","post_date":"2024-04-16 13:38:04","post_date_gmt":"2024-04-16 13:38:04","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa B","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-b","to_ping":"","pinged":"","post_modified":"2024-04-16 13:38:04","post_modified_gmt":"2024-04-16 13:38:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1069,"post_author":"1","post_date":"2024-04-16 13:38:16","post_date_gmt":"2024-04-16 13:38:16","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa C","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-c","to_ping":"","pinged":"","post_modified":"2024-04-16 13:38:16","post_modified_gmt":"2024-04-16 13:38:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1070,"post_author":"1","post_date":"2024-04-16 13:38:27","post_date_gmt":"2024-04-16 13:38:27","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa D","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-d","to_ping":"","pinged":"","post_modified":"2024-04-16 13:38:27","post_modified_gmt":"2024-04-16 13:38:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMonica_2024-cost_1I1-capas-48f-1.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":238,"name":"Costurada","slug":"costurada"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":267,"name":"80","slug":"80"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1058\/revisions"}],"predecessor-version":[{"id":2952,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1058\/revisions\/2952"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/4490"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1058"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1058"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1058"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1058"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1058"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1058"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1058"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1058"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1058"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":1061,"date":"2024-04-16T13:37:17","date_gmt":"2024-04-16T13:37:17","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-80-folhas-capa-b\/"},"modified":"2024-04-16T13:37:17","modified_gmt":"2024-04-16T13:37:17","slug":"turma-da-monica-caderno-brochura-1-1-80-folhas-capa-b","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-caderno-brochura-1-1-80-folhas-capa-b\/","title":{"rendered":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 80 folhas &#8211; Capa B"},"author":1,"featured_media":1062,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[38],"produto_capa":[227],"produto_lombada":[238],"produto_tipo_folha":[248],"produto_folha":[267],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,393,409,401],"class_list":["post-1061","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-brochurao-cd-costurado-1-1","produto_capa-dura","produto_lombada-costurada","produto_tipo_folha-pautado","produto_folha-267","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-cartela-de-adesivos-dupla","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca"],"acf":{"infos_produto":{"sku":"10429","ean":"7891321104293","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>A Turma da M\u00f4nica \u00e9 simplesmente imbat\u00edvel! Criada pelo talentoso Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira \u00e9 um verdadeiro tesouro nacional, amada por pessoas de todas as idades. E agora, voc\u00ea pode ter esses personagens incr\u00edveis em sua cole\u00e7\u00e3o da Animativa, garantindo momentos de pura divers\u00e3o e amor!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1058,1063,1065],"related_products":[{"ID":1067,"post_author":"1","post_date":"2024-04-16 13:37:52","post_date_gmt":"2024-04-16 13:37:52","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa A","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-a","to_ping":"","pinged":"","post_modified":"2024-04-16 13:37:52","post_modified_gmt":"2024-04-16 13:37:52","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1068,"post_author":"1","post_date":"2024-04-16 13:38:04","post_date_gmt":"2024-04-16 13:38:04","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa B","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-b","to_ping":"","pinged":"","post_modified":"2024-04-16 13:38:04","post_modified_gmt":"2024-04-16 13:38:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1069,"post_author":"1","post_date":"2024-04-16 13:38:16","post_date_gmt":"2024-04-16 13:38:16","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa C","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-c","to_ping":"","pinged":"","post_modified":"2024-04-16 13:38:16","post_modified_gmt":"2024-04-16 13:38:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1070,"post_author":"1","post_date":"2024-04-16 13:38:27","post_date_gmt":"2024-04-16 13:38:27","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa D","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-d","to_ping":"","pinged":"","post_modified":"2024-04-16 13:38:27","post_modified_gmt":"2024-04-16 13:38:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMonica_2024-cost_1I1-capas-48f-2.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":238,"name":"Costurada","slug":"costurada"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":267,"name":"80","slug":"80"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1061\/revisions"}],"predecessor-version":[{"id":2953,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1061\/revisions\/2953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/1062"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1061"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1061"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1061"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1061"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1061"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1061"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1061"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1061"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1061"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":1063,"date":"2024-04-16T13:37:29","date_gmt":"2024-04-16T13:37:29","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-80-folhas-capa-c\/"},"modified":"2024-04-16T13:37:29","modified_gmt":"2024-04-16T13:37:29","slug":"turma-da-monica-caderno-brochura-1-1-80-folhas-capa-c","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-caderno-brochura-1-1-80-folhas-capa-c\/","title":{"rendered":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 80 folhas &#8211; Capa C"},"author":1,"featured_media":1064,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[38],"produto_capa":[227],"produto_lombada":[238],"produto_tipo_folha":[248],"produto_folha":[267],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,393,409,401],"class_list":["post-1063","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-brochurao-cd-costurado-1-1","produto_capa-dura","produto_lombada-costurada","produto_tipo_folha-pautado","produto_folha-267","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-cartela-de-adesivos-dupla","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca"],"acf":{"infos_produto":{"sku":"10429","ean":"7891321104293","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>A Turma da M\u00f4nica \u00e9 simplesmente imbat\u00edvel! Criada pelo talentoso Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira \u00e9 um verdadeiro tesouro nacional, amada por pessoas de todas as idades. E agora, voc\u00ea pode ter esses personagens incr\u00edveis em sua cole\u00e7\u00e3o da Animativa, garantindo momentos de pura divers\u00e3o e amor!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1058,1061,1065],"related_products":[{"ID":1067,"post_author":"1","post_date":"2024-04-16 13:37:52","post_date_gmt":"2024-04-16 13:37:52","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa A","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-a","to_ping":"","pinged":"","post_modified":"2024-04-16 13:37:52","post_modified_gmt":"2024-04-16 13:37:52","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1068,"post_author":"1","post_date":"2024-04-16 13:38:04","post_date_gmt":"2024-04-16 13:38:04","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa B","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-b","to_ping":"","pinged":"","post_modified":"2024-04-16 13:38:04","post_modified_gmt":"2024-04-16 13:38:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1069,"post_author":"1","post_date":"2024-04-16 13:38:16","post_date_gmt":"2024-04-16 13:38:16","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa C","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-c","to_ping":"","pinged":"","post_modified":"2024-04-16 13:38:16","post_modified_gmt":"2024-04-16 13:38:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1070,"post_author":"1","post_date":"2024-04-16 13:38:27","post_date_gmt":"2024-04-16 13:38:27","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa D","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-d","to_ping":"","pinged":"","post_modified":"2024-04-16 13:38:27","post_modified_gmt":"2024-04-16 13:38:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMonica_2024-cost_1I1-capas-48f-3.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":238,"name":"Costurada","slug":"costurada"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":267,"name":"80","slug":"80"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1063\/revisions"}],"predecessor-version":[{"id":2954,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1063\/revisions\/2954"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/1064"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1063"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1063"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1063"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1063"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1063"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1063"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1063"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1063"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1063"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":1065,"date":"2024-04-16T13:37:40","date_gmt":"2024-04-16T13:37:40","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-80-folhas-capa-d\/"},"modified":"2024-04-16T13:37:40","modified_gmt":"2024-04-16T13:37:40","slug":"turma-da-monica-caderno-brochura-1-1-80-folhas-capa-d","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-caderno-brochura-1-1-80-folhas-capa-d\/","title":{"rendered":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 80 folhas &#8211; Capa D"},"author":1,"featured_media":1066,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[38],"produto_capa":[227],"produto_lombada":[238],"produto_tipo_folha":[248],"produto_folha":[267],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,393,409,401],"class_list":["post-1065","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-brochurao-cd-costurado-1-1","produto_capa-dura","produto_lombada-costurada","produto_tipo_folha-pautado","produto_folha-267","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-cartela-de-adesivos-dupla","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca"],"acf":{"infos_produto":{"sku":"10429","ean":"7891321104293","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>A Turma da M\u00f4nica \u00e9 simplesmente imbat\u00edvel! Criada pelo talentoso Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira \u00e9 um verdadeiro tesouro nacional, amada por pessoas de todas as idades. E agora, voc\u00ea pode ter esses personagens incr\u00edveis em sua cole\u00e7\u00e3o da Animativa, garantindo momentos de pura divers\u00e3o e amor!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1058,1061,1063],"related_products":[{"ID":1067,"post_author":"1","post_date":"2024-04-16 13:37:52","post_date_gmt":"2024-04-16 13:37:52","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa A","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-a","to_ping":"","pinged":"","post_modified":"2024-04-16 13:37:52","post_modified_gmt":"2024-04-16 13:37:52","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1068,"post_author":"1","post_date":"2024-04-16 13:38:04","post_date_gmt":"2024-04-16 13:38:04","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa B","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-b","to_ping":"","pinged":"","post_modified":"2024-04-16 13:38:04","post_modified_gmt":"2024-04-16 13:38:04","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1069,"post_author":"1","post_date":"2024-04-16 13:38:16","post_date_gmt":"2024-04-16 13:38:16","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa C","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-c","to_ping":"","pinged":"","post_modified":"2024-04-16 13:38:16","post_modified_gmt":"2024-04-16 13:38:16","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1070,"post_author":"1","post_date":"2024-04-16 13:38:27","post_date_gmt":"2024-04-16 13:38:27","post_content":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_title":"Turma da M\u00f4nica \u2013 Caderno Brochura 1\/1- 48 folhas - Capa D","post_excerpt":"Quem cresceu lendo os quadrinhos da Turma da M\u00f4nica sabe como \u00e9 especial essa turminha criada pelo incr\u00edvel Maur\u00edcio de Sousa. Desde 1959, eles fazem parte da nossa cultura e continuam encantando gera\u00e7\u00f5es. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e se divertir com hist\u00f3rias cheias de amor e divers\u00e3o!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-caderno-brochura-1-1-48-folhas-capa-d","to_ping":"","pinged":"","post_modified":"2024-04-16 13:38:27","post_modified_gmt":"2024-04-16 13:38:27","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-caderno-brochura-1-1-48-folhas-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMonica_2024-cost_1I1-capas-48f-4.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":238,"name":"Costurada","slug":"costurada"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":267,"name":"80","slug":"80"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1065\/revisions"}],"predecessor-version":[{"id":2955,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1065\/revisions\/2955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/1066"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1065"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1065"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1065"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1065"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1065"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1065"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1065"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1065"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1065"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMonica_2024-cost_1I1-capas-48f-1.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":238,"name":"Costurada","slug":"costurada"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":296,"name":"48","slug":"48"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1067\/revisions"}],"predecessor-version":[{"id":2956,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1067\/revisions\/2956"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/4490"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1067"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1067"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1067"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1067"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1067"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1067"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1067"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1067"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1067"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}