{"id":1054,"date":"2024-04-16T13:35:41","date_gmt":"2024-04-16T13:35:41","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-a\/"},"modified":"2024-04-16T13:35:41","modified_gmt":"2024-04-16T13:35:41","slug":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-a","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-a\/","title":{"rendered":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias &#8211; Capa A"},"author":1,"featured_media":4462,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[269],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409,401,404,407],"class_list":["post-1054","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-269","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca","produto_caracteristica-libras","produto_caracteristica-uv-reserva"],"acf":{"infos_produto":{"sku":"10267","ean":"7891321102671","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1055,1056,1057],"related_products":[{"id":1043,"date":"2024-04-16T13:34:18","date_gmt":"2024-04-16T13:34:18","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-1materia-capa-a\/"},"modified":"2024-04-16T13:34:18","modified_gmt":"2024-04-16T13:34:18","slug":"turma-da-monica-60-anos-caderno-universitario-1materia-capa-a","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-60-anos-caderno-universitario-1materia-capa-a\/","title":{"rendered":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 1Mat\u00e9ria &#8211; Capa A"},"author":1,"featured_media":4462,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[267],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409,401,404,407],"class_list":["post-1043","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-267","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca","produto_caracteristica-libras","produto_caracteristica-uv-reserva"],"acf":{"infos_produto":{"sku":"10266","ean":"7891321102664","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Quem n\u00e3o ama a Turma da M\u00f4nica, n\u00e9? Esses quadrinhos brasileiros criados pelo talentoso Maur\u00edcio de Sousa s\u00e3o verdadeiros cl\u00e1ssicos que marcaram \u00e9poca e continuam encantando o p\u00fablico at\u00e9 hoje. E agora voc\u00ea pode ter esses personagens queridos em sua cole\u00e7\u00e3o da Animativa, trazendo muita divers\u00e3o e amor para o seu dia a dia!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1048,1050,1052],"related_products":[{"ID":1054,"post_author":"1","post_date":"2024-04-16 13:35:41","post_date_gmt":"2024-04-16 13:35:41","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa A","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-04-16 13:35:41","post_modified_gmt":"2024-04-16 13:35:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1055,"post_author":"1","post_date":"2024-04-16 13:36:02","post_date_gmt":"2024-04-16 13:36:02","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa B","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-04-16 13:36:02","post_modified_gmt":"2024-04-16 13:36:02","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1056,"post_author":"1","post_date":"2024-04-16 13:36:23","post_date_gmt":"2024-04-16 13:36:23","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa C","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-04-16 13:36:23","post_modified_gmt":"2024-04-16 13:36:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1057,"post_author":"1","post_date":"2024-04-16 13:36:44","post_date_gmt":"2024-04-16 13:36:44","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa D","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-04-16 13:36:44","post_modified_gmt":"2024-04-16 13:36:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMocc82nica-Capa01.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":267,"name":"80","slug":"80"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1043\/revisions"}],"predecessor-version":[{"id":2944,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1043\/revisions\/2944"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/4462"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1043"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1043"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1043"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1043"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1043"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1043"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1043"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1043"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1043"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":1048,"date":"2024-04-16T13:34:39","date_gmt":"2024-04-16T13:34:39","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-1materia-capa-b\/"},"modified":"2024-04-16T13:34:39","modified_gmt":"2024-04-16T13:34:39","slug":"turma-da-monica-60-anos-caderno-universitario-1materia-capa-b","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-60-anos-caderno-universitario-1materia-capa-b\/","title":{"rendered":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 1Mat\u00e9ria &#8211; Capa B"},"author":1,"featured_media":4466,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[267],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409,401,404,407],"class_list":["post-1048","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-267","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca","produto_caracteristica-libras","produto_caracteristica-uv-reserva"],"acf":{"infos_produto":{"sku":"10266","ean":"7891321102664","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Quem n\u00e3o ama a Turma da M\u00f4nica, n\u00e9? Esses quadrinhos brasileiros criados pelo talentoso Maur\u00edcio de Sousa s\u00e3o verdadeiros cl\u00e1ssicos que marcaram \u00e9poca e continuam encantando o p\u00fablico at\u00e9 hoje. E agora voc\u00ea pode ter esses personagens queridos em sua cole\u00e7\u00e3o da Animativa, trazendo muita divers\u00e3o e amor para o seu dia a dia!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1043,1050,1052],"related_products":[{"ID":1054,"post_author":"1","post_date":"2024-04-16 13:35:41","post_date_gmt":"2024-04-16 13:35:41","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa A","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-04-16 13:35:41","post_modified_gmt":"2024-04-16 13:35:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1055,"post_author":"1","post_date":"2024-04-16 13:36:02","post_date_gmt":"2024-04-16 13:36:02","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa B","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-04-16 13:36:02","post_modified_gmt":"2024-04-16 13:36:02","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1056,"post_author":"1","post_date":"2024-04-16 13:36:23","post_date_gmt":"2024-04-16 13:36:23","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa C","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-04-16 13:36:23","post_modified_gmt":"2024-04-16 13:36:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1057,"post_author":"1","post_date":"2024-04-16 13:36:44","post_date_gmt":"2024-04-16 13:36:44","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa D","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-04-16 13:36:44","post_modified_gmt":"2024-04-16 13:36:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMocc82nica-Capa02.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":267,"name":"80","slug":"80"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1048\/revisions"}],"predecessor-version":[{"id":2945,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1048\/revisions\/2945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/4466"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1048"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1048"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1048"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1048"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1048"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1048"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1048"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1048"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1048"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":1050,"date":"2024-04-16T13:34:59","date_gmt":"2024-04-16T13:34:59","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-1materia-capa-c\/"},"modified":"2024-04-16T13:34:59","modified_gmt":"2024-04-16T13:34:59","slug":"turma-da-monica-60-anos-caderno-universitario-1materia-capa-c","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-60-anos-caderno-universitario-1materia-capa-c\/","title":{"rendered":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 1Mat\u00e9ria &#8211; Capa C"},"author":1,"featured_media":4470,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[267],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409,401,404,407],"class_list":["post-1050","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-267","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca","produto_caracteristica-libras","produto_caracteristica-uv-reserva"],"acf":{"infos_produto":{"sku":"10266","ean":"7891321102664","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Quem n\u00e3o ama a Turma da M\u00f4nica, n\u00e9? Esses quadrinhos brasileiros criados pelo talentoso Maur\u00edcio de Sousa s\u00e3o verdadeiros cl\u00e1ssicos que marcaram \u00e9poca e continuam encantando o p\u00fablico at\u00e9 hoje. E agora voc\u00ea pode ter esses personagens queridos em sua cole\u00e7\u00e3o da Animativa, trazendo muita divers\u00e3o e amor para o seu dia a dia!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1043,1048,1052],"related_products":[{"ID":1054,"post_author":"1","post_date":"2024-04-16 13:35:41","post_date_gmt":"2024-04-16 13:35:41","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa A","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-04-16 13:35:41","post_modified_gmt":"2024-04-16 13:35:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1055,"post_author":"1","post_date":"2024-04-16 13:36:02","post_date_gmt":"2024-04-16 13:36:02","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa B","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-04-16 13:36:02","post_modified_gmt":"2024-04-16 13:36:02","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1056,"post_author":"1","post_date":"2024-04-16 13:36:23","post_date_gmt":"2024-04-16 13:36:23","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa C","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-04-16 13:36:23","post_modified_gmt":"2024-04-16 13:36:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1057,"post_author":"1","post_date":"2024-04-16 13:36:44","post_date_gmt":"2024-04-16 13:36:44","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa D","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-04-16 13:36:44","post_modified_gmt":"2024-04-16 13:36:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMoCC82nica-Capa03.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":267,"name":"80","slug":"80"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1050\/revisions"}],"predecessor-version":[{"id":2946,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1050\/revisions\/2946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/4470"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1050"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1050"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1050"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1050"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1050"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1050"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1050"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1050"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1050"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},{"id":1052,"date":"2024-04-16T13:35:20","date_gmt":"2024-04-16T13:35:20","guid":{"rendered":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-1materia-capa-d\/"},"modified":"2024-04-16T13:35:20","modified_gmt":"2024-04-16T13:35:20","slug":"turma-da-monica-60-anos-caderno-universitario-1materia-capa-d","status":"publish","type":"produtos","link":"https:\/\/dev.animativa.com\/en\/p\/turma-da-monica-60-anos-caderno-universitario-1materia-capa-d\/","title":{"rendered":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 1Mat\u00e9ria &#8211; Capa D"},"author":1,"featured_media":4474,"template":"","meta":{"_acf_changed":false},"categoria_produtos":[37],"produto_capa":[227],"produto_lombada":[237],"produto_tipo_folha":[248],"produto_folha":[267],"produto_gramatura":[300],"produto_formato_mm":[307],"produto_selo":[362],"produto_caracteristica":[392,409,401,404,407],"class_list":["post-1052","produtos","type-produtos","status-publish","has-post-thumbnail","hentry","categoria_produtos-universitario","produto_capa-dura","produto_lombada-espiral","produto_tipo_folha-pautado","produto_folha-267","produto_gramatura-300","produto_formato_mm-200x275","produto_selo-produto-certificado-fsc-misto","produto_caracteristica-cartela-de-adesivos","produto_caracteristica-gramatura","produto_caracteristica-laminacao-fosca","produto_caracteristica-libras","produto_caracteristica-uv-reserva"],"acf":{"infos_produto":{"sku":"10266","ean":"7891321102664","ano_de_lancamento":"2023","garantia":"30 dias"},"release":false,"faq":{"datails_editor":"<p>Quem n\u00e3o ama a Turma da M\u00f4nica, n\u00e9? Esses quadrinhos brasileiros criados pelo talentoso Maur\u00edcio de Sousa s\u00e3o verdadeiros cl\u00e1ssicos que marcaram \u00e9poca e continuam encantando o p\u00fablico at\u00e9 hoje. E agora voc\u00ea pode ter esses personagens queridos em sua cole\u00e7\u00e3o da Animativa, trazendo muita divers\u00e3o e amor para o seu dia a dia!<\/p>\n"},"features":{"gramatura":"56","ponta":"","lavavel":""},"acessorios":{"bolsa":true,"adesivos":true},"variants":[1043,1048,1050],"related_products":[{"ID":1054,"post_author":"1","post_date":"2024-04-16 13:35:41","post_date_gmt":"2024-04-16 13:35:41","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa A","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-a","to_ping":"","pinged":"","post_modified":"2024-04-16 13:35:41","post_modified_gmt":"2024-04-16 13:35:41","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-a\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1055,"post_author":"1","post_date":"2024-04-16 13:36:02","post_date_gmt":"2024-04-16 13:36:02","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa B","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-b","to_ping":"","pinged":"","post_modified":"2024-04-16 13:36:02","post_modified_gmt":"2024-04-16 13:36:02","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-b\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1056,"post_author":"1","post_date":"2024-04-16 13:36:23","post_date_gmt":"2024-04-16 13:36:23","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa C","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-c","to_ping":"","pinged":"","post_modified":"2024-04-16 13:36:23","post_modified_gmt":"2024-04-16 13:36:23","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-c\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":1057,"post_author":"1","post_date":"2024-04-16 13:36:44","post_date_gmt":"2024-04-16 13:36:44","post_content":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_title":"Turma da M\u00f4nica 60 anos \u2013 Caderno Universit\u00e1rio 10 Mat\u00e9rias - Capa D","post_excerpt":"Prepare-se para embarcar em uma viagem nost\u00e1lgica com a Turma da M\u00f4nica! Criada pelo genial Maur\u00edcio de Sousa, essa s\u00e9rie de quadrinhos brasileira conquistou cora\u00e7\u00f5es desde 1959 e continua sendo um sucesso absoluto. Agora, voc\u00ea pode trazer toda essa magia para sua cole\u00e7\u00e3o da Animativa e reviver momentos incr\u00edveis cheios de divers\u00e3o e amor!","post_status":"publish","comment_status":"open","ping_status":"open","post_password":"","post_name":"turma-da-monica-60-anos-caderno-universitario-10-materias-capa-d","to_ping":"","pinged":"","post_modified":"2024-04-16 13:36:44","post_modified_gmt":"2024-04-16 13:36:44","post_content_filtered":"","post_parent":0,"guid":"http:\/\/animativa.local\/produtos\/turma-da-monica-60-anos-caderno-universitario-10-materias-capa-d\/","menu_order":0,"post_type":"produtos","post_mime_type":"","comment_count":"0","filter":"raw"}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMocc82nica-Capa04.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":267,"name":"80","slug":"80"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1052\/revisions"}],"predecessor-version":[{"id":2947,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1052\/revisions\/2947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/4474"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1052"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1052"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1052"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1052"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1052"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1052"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1052"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1052"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1052"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}],"images":false,"product_type":85,"brand":101},"productType":{"id":85,"date":"2024-03-12T16:38:18","date_gmt":"2024-03-12T16:38:18","guid":{"rendered":"http:\/\/animativa.local\/?post_type=tipos_produto&#038;p=85"},"modified":"2024-08-29T16:57:19","modified_gmt":"2024-08-29T19:57:19","slug":"cadernos","status":"publish","type":"tipos_produto","link":"https:\/\/dev.animativa.com\/en\/nossos-produtos\/cadernos\/","title":{"rendered":"Cadernos"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-85","tipos_produto","type-tipos_produto","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/tipos_produto"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":66,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions"}],"predecessor-version":[{"id":29747,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/tipos_produto\/85\/revisions\/29747"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"productBrand":{"id":101,"date":"2024-04-15T21:20:09","date_gmt":"2024-04-15T21:20:09","guid":{"rendered":"http:\/\/animativa.local\/?post_type=marcas_produtos&#038;p=101"},"modified":"2024-08-08T18:00:08","modified_gmt":"2024-08-08T21:00:08","slug":"turma-da-monica","status":"publish","type":"marcas","link":"https:\/\/dev.animativa.com\/en\/marcas\/turma-da-monica\/","title":{"rendered":"Turma da M\u00f4nica"},"author":1,"template":"","meta":{"_acf_changed":false},"class_list":["post-101","marcas","type-marcas","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/marcas"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":22,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions"}],"predecessor-version":[{"id":19686,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/marcas\/101\/revisions\/19686"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}},"featuredMedia":"https:\/\/dev.animativa.com\/wp-content\/uploads\/2024\/04\/TurmadaMocc82nica-Capa01.png","taxonomies":{"produto_capa":[{"ID":227,"name":"Dura","slug":"dura"}],"produto_lombada":[{"ID":237,"name":"Espiral","slug":"espiral"}],"produto_tipo_folha":[{"ID":248,"name":"Pautado","slug":"pautado"}],"produto_folha":[{"ID":269,"name":"160","slug":"160"}],"produto_gramatura":[{"ID":300,"name":"56","slug":"56"}],"produto_formato_mm":[{"ID":307,"name":"200x275","slug":"200x275"}],"produto_selo":[{"ID":362,"name":"Produto Certificado: FSC\u00ae Misto","slug":"produto-certificado-fsc-misto"}]},"_links":{"self":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos"}],"about":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/types\/produtos"}],"author":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1054\/revisions"}],"predecessor-version":[{"id":2948,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produtos\/1054\/revisions\/2948"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media\/4462"}],"wp:attachment":[{"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/media?parent=1054"}],"wp:term":[{"taxonomy":"categoria_produtos","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/categoria_produtos?post=1054"},{"taxonomy":"produto_capa","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_capa?post=1054"},{"taxonomy":"produto_lombada","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_lombada?post=1054"},{"taxonomy":"produto_tipo_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_tipo_folha?post=1054"},{"taxonomy":"produto_folha","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_folha?post=1054"},{"taxonomy":"produto_gramatura","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_gramatura?post=1054"},{"taxonomy":"produto_formato_mm","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_formato_mm?post=1054"},{"taxonomy":"produto_selo","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_selo?post=1054"},{"taxonomy":"produto_caracteristica","embeddable":true,"href":"https:\/\/dev.animativa.com\/en\/wp-json\/wp\/v2\/produto_caracteristica?post=1054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}